{"id":250,"date":"2018-05-15T22:31:29","date_gmt":"2018-05-15T20:31:29","guid":{"rendered":"http:\/\/www.shopping-club.com\/de\/?page_id=250"},"modified":"2020-02-24T00:50:58","modified_gmt":"2020-02-23T22:50:58","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/www.shopping-club.com\/de\/datenschutzerklaerung","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"<h4>Datenschutzerkl\u00e4rung<\/h4>\n<p>Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung der shopping-club.com. Eine Nutzung der Internetseiten der shopping-club.com ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch eine Verarbeitung personenbezogener Daten erforderlich werden. Ist die Verarbeitung personenbezogener Daten erforderlich und besteht f\u00fcr eine solche Verarbeitung keine gesetzliche Grundlage, holen wir generell eine Einwilligung der betroffenen Person ein.<\/p>\n<p>Die Verarbeitung personenbezogener Daten, beispielsweise des Namens, der Anschrift, E-Mail-Adresse oder Telefonnummer einer betroffenen Person, erfolgt stets im Einklang mit der Datenschutz-Grundverordnung und in \u00dcbereinstimmung mit den f\u00fcr die shopping-club.com geltenden landesspezifischen Datenschutzbestimmungen. Mittels dieser Datenschutzerkl\u00e4rung m\u00f6chte unser Unternehmen die \u00d6ffentlichkeit \u00fcber Art, Umfang und Zweck der von uns erhobenen, genutzten und verarbeiteten personenbezogenen Daten informieren. Ferner werden betroffene Personen mittels dieser Datenschutzerkl\u00e4rung \u00fcber die ihnen zustehenden Rechte aufgekl\u00e4rt.<\/p>\n<p>Die shopping-club.com hat als f\u00fcr die Verarbeitung Verantwortlicher zahlreiche technische und organisatorische Ma\u00dfnahmen umgesetzt, um einen m\u00f6glichst l\u00fcckenlosen Schutz der \u00fcber diese Internetseite verarbeiteten personenbezogenen Daten sicherzustellen. Dennoch k\u00f6nnen Internetbasierte Daten\u00fcbertragungen grunds\u00e4tzlich Sicherheitsl\u00fccken aufweisen, sodass ein absoluter Schutz nicht gew\u00e4hrleistet werden kann. Aus diesem Grund steht es jeder betroffenen Person frei, personenbezogene Daten auch auf alternativen Wegen, beispielsweise telefonisch, an uns zu \u00fcbermitteln.<\/p>\n<h4>1. Begriffsbestimmungen<\/h4>\n<p>Die Datenschutzerkl\u00e4rung der shopping-club.com beruht auf den Begrifflichkeiten, die durch den Europ\u00e4ischen Richtlinien- und Verordnungsgeber beim Erlass der Datenschutz-Grundverordnung (DS-GVO) verwendet wurden. Unsere Datenschutzerkl\u00e4rung soll sowohl f\u00fcr die \u00d6ffentlichkeit als auch f\u00fcr unsere Kunden und Gesch\u00e4ftspartner einfach lesbar und verst\u00e4ndlich sein. Um dies zu gew\u00e4hrleisten, m\u00f6chten wir vorab die verwendeten Begrifflichkeiten erl\u00e4utern.<\/p>\n<p>Wir verwenden in dieser Datenschutzerkl\u00e4rung unter anderem die folgenden Begriffe:<\/p>\n<ul style=\"list-style: none\">\n<li>\n<h4>a)    personenbezogene Daten<\/h4>\n<p>Personenbezogene Daten sind alle Informationen, die sich auf eine identifizierte oder identifizierbare nat\u00fcrliche Person (im Folgenden \u201ebetroffene Person\u201c) beziehen. Als identifizierbar wird eine nat\u00fcrliche Person angesehen, die direkt oder indirekt, insbesondere mittels Zuordnung zu einer Kennung wie einem Namen, zu einer Kennnummer, zu Standortdaten, zu einer Online-Kennung oder zu einem oder mehreren besonderen Merkmalen, die Ausdruck der physischen, physiologischen, genetischen, psychischen, wirtschaftlichen, kulturellen oder sozialen Identit\u00e4t dieser nat\u00fcrlichen Person sind, identifiziert werden kann.<\/p>\n<\/li>\n<li>\n<h4>b)    betroffene Person<\/h4>\n<p>Betroffene Person ist jede identifizierte oder identifizierbare nat\u00fcrliche Person, deren personenbezogene Daten von dem f\u00fcr die Verarbeitung Verantwortlichen verarbeitet werden.<\/p>\n<\/li>\n<li>\n<h4>c)    Verarbeitung<\/h4>\n<p>Verarbeitung ist jeder mit oder ohne Hilfe automatisierter Verfahren ausgef\u00fchrte Vorgang oder jede solche Vorgangsreihe im Zusammenhang mit personenbezogenen Daten wie das Erheben, das Erfassen, die Organisation, das Ordnen, die Speicherung, die Anpassung oder Ver\u00e4nderung, das Auslesen, das Abfragen, die Verwendung, die Offenlegung durch \u00dcbermittlung, Verbreitung oder eine andere Form der Bereitstellung, den Abgleich oder die Verkn\u00fcpfung, die Einschr\u00e4nkung, das L\u00f6schen oder die Vernichtung.<\/p>\n<\/li>\n<li>\n<h4>d)    Einschr\u00e4nkung der Verarbeitung<\/h4>\n<p>Einschr\u00e4nkung der Verarbeitung ist die Markierung gespeicherter personenbezogener Daten mit dem Ziel, ihre k\u00fcnftige Verarbeitung einzuschr\u00e4nken.<\/p>\n<\/li>\n<li>\n<h4>e)    Profiling<\/h4>\n<p>Profiling ist jede Art der automatisierten Verarbeitung personenbezogener Daten, die darin besteht, dass diese personenbezogenen Daten verwendet werden, um bestimmte pers\u00f6nliche Aspekte, die sich auf eine nat\u00fcrliche Person beziehen, zu bewerten, insbesondere, um Aspekte bez\u00fcglich Arbeitsleistung, wirtschaftlicher Lage, Gesundheit, pers\u00f6nlicher Vorlieben, Interessen, Zuverl\u00e4ssigkeit, Verhalten, Aufenthaltsort oder Ortswechsel dieser nat\u00fcrlichen Person zu analysieren oder vorherzusagen.<\/p>\n<\/li>\n<li>\n<h4>f)     Pseudonymisierung<\/h4>\n<p>Pseudonymisierung ist die Verarbeitung personenbezogener Daten in einer Weise, auf welche die personenbezogenen Daten ohne Hinzuziehung zus\u00e4tzlicher Informationen nicht mehr einer spezifischen betroffenen Person zugeordnet werden k\u00f6nnen, sofern diese zus\u00e4tzlichen Informationen gesondert aufbewahrt werden und technischen und organisatorischen Ma\u00dfnahmen unterliegen, die gew\u00e4hrleisten, dass die personenbezogenen Daten nicht einer identifizierten oder identifizierbaren nat\u00fcrlichen Person zugewiesen werden.<\/p>\n<\/li>\n<li>\n<h4>g)    Verantwortlicher oder f\u00fcr die Verarbeitung Verantwortlicher<\/h4>\n<p>Verantwortlicher oder f\u00fcr die Verarbeitung Verantwortlicher ist die nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten entscheidet. Sind die Zwecke und Mittel dieser Verarbeitung durch das Unionsrecht oder das Recht der Mitgliedstaaten vorgegeben, so kann der Verantwortliche beziehungsweise k\u00f6nnen die bestimmten Kriterien seiner Benennung nach dem Unionsrecht oder dem Recht der Mitgliedstaaten vorgesehen werden.<\/p>\n<\/li>\n<li>\n<h4>h)    Auftragsverarbeiter<\/h4>\n<p>Auftragsverarbeiter ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, die personenbezogene Daten im Auftrag des Verantwortlichen verarbeitet.<\/p>\n<\/li>\n<li>\n<h4>i)      Empf\u00e4nger<\/h4>\n<p>Empf\u00e4nger ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, der personenbezogene Daten offengelegt werden, unabh\u00e4ngig davon, ob es sich bei ihr um einen Dritten handelt oder nicht. Beh\u00f6rden, die im Rahmen eines bestimmten Untersuchungsauftrags nach dem Unionsrecht oder dem Recht der Mitgliedstaaten m\u00f6glicherweise personenbezogene Daten erhalten, gelten jedoch nicht als Empf\u00e4nger.<\/p>\n<\/li>\n<li>\n<h4>j)      Dritter<\/h4>\n<p>Dritter ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle au\u00dfer der betroffenen Person, dem Verantwortlichen, dem Auftragsverarbeiter und den Personen, die unter der unmittelbaren Verantwortung des Verantwortlichen oder des Auftragsverarbeiters befugt sind, die personenbezogenen Daten zu verarbeiten.<\/p>\n<\/li>\n<li>\n<h4>k)    Einwilligung<\/h4>\n<p>Einwilligung ist jede von der betroffenen Person freiwillig f\u00fcr den bestimmten Fall in informierter Weise und unmissverst\u00e4ndlich abgegebene Willensbekundung in Form einer Erkl\u00e4rung oder einer sonstigen eindeutigen best\u00e4tigenden Handlung, mit der die betroffene Person zu verstehen gibt, dass sie mit der Verarbeitung der sie betreffenden personenbezogenen Daten einverstanden ist.<\/p>\n<\/li>\n<\/ul>\n<h4>2. Name und Anschrift des f\u00fcr die Verarbeitung Verantwortlichen<\/h4>\n<p>Verantwortlicher im Sinne der Datenschutz-Grundverordnung, sonstiger in den Mitgliedstaaten der Europ\u00e4ischen Union geltenden Datenschutzgesetze und anderer Bestimmungen mit datenschutzrechtlichem Charakter ist die: Mi\u0441ha\u0435l K\u043egan; Aschbachring 61, 66127 Saarbr\u00fccken; Em\u0430il:info[\u0430\u0442]kumk.de<\/p>\n<p><a id=\"toCookies\"><\/a><\/p>\n<h4>3. Cookies<\/h4>\n<p>Die Internetseiten der shopping-club.com verwenden Cookies. Cookies sind Textdateien, welche \u00fcber einen Internetbrowser auf einem Computersystem abgelegt und gespeichert werden.<\/p>\n<p>Zahlreiche Internetseiten und Server verwenden Cookies. Viele Cookies enthalten eine sogenannte Cookie-ID. Eine Cookie-ID ist eine eindeutige Kennung des Cookies. Sie besteht aus einer Zeichenfolge, durch welche Internetseiten und Server dem konkreten Internetbrowser zugeordnet werden k\u00f6nnen, in dem das Cookie gespeichert wurde. Dies erm\u00f6glicht es den besuchten Internetseiten und Servern, den individuellen Browser der betroffenen Person von anderen Internetbrowsern, die andere Cookies enthalten, zu unterscheiden. Ein bestimmter Internetbrowser kann \u00fcber die eindeutige Cookie-ID wiedererkannt und identifiziert werden.<\/p>\n<p>Durch den Einsatz von Cookies kann die shopping-club.com den Nutzern dieser Internetseite nutzerfreundlichere Services bereitstellen, die ohne die Cookie-Setzung nicht m\u00f6glich w\u00e4ren.<\/p>\n<p>Mittels eines Cookies k\u00f6nnen die Informationen und Angebote auf unserer Internetseite im Sinne des Benutzers optimiert werden. Cookies erm\u00f6glichen uns, wie bereits erw\u00e4hnt, die Benutzer unserer Internetseite wiederzuerkennen. Zweck dieser Wiedererkennung ist es, den Nutzern die Verwendung unserer Internetseite zu erleichtern. Der Benutzer einer Internetseite, die Cookies verwendet, muss beispielsweise nicht bei jedem Besuch der Internetseite erneut seine Zugangsdaten eingeben, weil dies von der Internetseite und dem auf dem Computersystem des Benutzers abgelegten Cookie \u00fcbernommen wird. Ein weiteres Beispiel ist das Cookie eines Warenkorbes im Online-Shop. Der Online-Shop merkt sich die Artikel, die ein Kunde in den virtuellen Warenkorb gelegt hat, \u00fcber ein Cookie.<\/p>\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Ferner k\u00f6nnen bereits gesetzte Cookies jederzeit \u00fcber einen Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden. Dies ist in allen g\u00e4ngigen Internetbrowsern m\u00f6glich. Deaktiviert die betroffene Person die Setzung von Cookies in dem genutzten Internetbrowser, sind unter Umst\u00e4nden nicht alle Funktionen unserer Internetseite vollumf\u00e4nglich nutzbar.<\/p>\n<h4>4. Erfassung von allgemeinen Daten und Informationen<\/h4>\n<p>Die Internetseite der shopping-club.com erfasst mit jedem Aufruf der Internetseite durch eine betroffene Person oder ein automatisiertes System eine Reihe von allgemeinen Daten und Informationen. Diese allgemeinen Daten und Informationen werden in den Logfiles des Servers gespeichert. Erfasst werden k\u00f6nnen die (1) verwendeten Browsertypen und Versionen, (2) das vom zugreifenden System verwendete Betriebssystem, (3) die Internetseite, von welcher ein zugreifendes System auf unsere Internetseite gelangt (sogenannte Referrer), (4) die Unterwebseiten, welche \u00fcber ein zugreifendes System auf unserer Internetseite angesteuert werden, (5) das Datum und die Uhrzeit eines Zugriffs auf die Internetseite, (6) eine Internet-Protokoll-Adresse (IP-Adresse), (7) der Internet-Service-Provider des zugreifenden Systems und (8) sonstige \u00e4hnliche Daten und Informationen, die der Gefahrenabwehr im Falle von Angriffen auf unsere informationstechnologischen Systeme dienen.<\/p>\n<p>Bei der Nutzung dieser allgemeinen Daten und Informationen zieht die shopping-club.com keine R\u00fcckschl\u00fcsse auf die betroffene Person. Diese Informationen werden vielmehr ben\u00f6tigt, um (1) die Inhalte unserer Internetseite korrekt auszuliefern, (2) die Inhalte unserer Internetseite sowie die Werbung f\u00fcr diese zu optimieren, (3) die dauerhafte Funktionsf\u00e4higkeit unserer informationstechnologischen Systeme und der Technik unserer Internetseite zu gew\u00e4hrleisten sowie (4) um Strafverfolgungsbeh\u00f6rden im Falle eines Cyberangriffes die zur Strafverfolgung notwendigen Informationen bereitzustellen. Diese anonym erhobenen Daten und Informationen werden durch die shopping-club.com daher einerseits statistisch und ferner mit dem Ziel ausgewertet, den Datenschutz und die Datensicherheit in unserem Unternehmen zu erh\u00f6hen, um letztlich ein optimales Schutzniveau f\u00fcr die von uns verarbeiteten personenbezogenen Daten sicherzustellen. Die anonymen Daten der Server-Logfiles werden getrennt von allen durch eine betroffene Person angegebenen personenbezogenen Daten gespeichert.<\/p>\n<h4>5. Kontaktm\u00f6glichkeit \u00fcber die Internetseite<\/h4>\n<p>Die Internetseite der shopping-club.com enth\u00e4lt aufgrund von gesetzlichen Vorschriften Angaben, die eine schnelle elektronische Kontaktaufnahme zu unserem Unternehmen sowie eine unmittelbare Kommunikation mit uns erm\u00f6glichen, was ebenfalls eine allgemeine Adresse der sogenannten elektronischen Post (E-Mail-Adresse) umfasst. Sofern eine betroffene Person per E-Mail oder \u00fcber ein Kontaktformular den Kontakt mit dem f\u00fcr die Verarbeitung Verantwortlichen aufnimmt, werden die von der betroffenen Person \u00fcbermittelten personenbezogenen Daten automatisch gespeichert. Solche auf freiwilliger Basis von einer betroffenen Person an den f\u00fcr die Verarbeitung Verantwortlichen \u00fcbermittelten personenbezogenen Daten werden f\u00fcr Zwecke der Bearbeitung oder der Kontaktaufnahme zur betroffenen Person gespeichert. Es erfolgt keine Weitergabe dieser personenbezogenen Daten an Dritte.<\/p>\n<h4>6. Kommentarfunktion im Blog auf der Internetseite<\/h4>\n<p>Die shopping-club.com bietet den Nutzern auf einem Blog, der sich auf der Internetseite des f\u00fcr die Verarbeitung Verantwortlichen befindet, die M\u00f6glichkeit, individuelle Kommentare zu einzelnen Blog-Beitr\u00e4gen zu hinterlassen. Ein Blog ist ein auf einer Internetseite gef\u00fchrtes, in der Regel \u00f6ffentlich einsehbares Portal, in welchem eine oder mehrere Personen, die Blogger oder Web-Blogger genannt werden, Artikel posten oder Gedanken in sogenannten Blogposts niederschreiben k\u00f6nnen. Die Blogposts k\u00f6nnen in der Regel von Dritten kommentiert werden.<\/p>\n<p>Hinterl\u00e4sst eine betroffene Person einen Kommentar in dem auf dieser Internetseite ver\u00f6ffentlichten Blog, werden neben den von der betroffenen Person hinterlassenen Kommentaren auch Angaben zum Zeitpunkt der Kommentareingabe sowie zu dem von der betroffenen Person gew\u00e4hlten Nutzernamen (Pseudonym) gespeichert und ver\u00f6ffentlicht. Ferner wird die vom Internet-Service-Provider (ISP) der betroffenen Person vergebene IP-Adresse mitprotokolliert. Diese Speicherung der IP-Adresse erfolgt aus Sicherheitsgr\u00fcnden und f\u00fcr den Fall, dass die betroffene Person durch einen abgegebenen Kommentar die Rechte Dritter verletzt oder rechtswidrige Inhalte postet. Die Speicherung dieser personenbezogenen Daten erfolgt daher im eigenen Interesse des f\u00fcr die Verarbeitung Verantwortlichen, damit sich dieser im Falle einer Rechtsverletzung gegebenenfalls exkulpieren k\u00f6nnte. Es erfolgt keine Weitergabe dieser erhobenen personenbezogenen Daten an Dritte, sofern eine solche Weitergabe nicht gesetzlich vorgeschrieben ist oder der Rechtsverteidigung des f\u00fcr die Verarbeitung Verantwortlichen dient.<\/p>\n<h4>7. Abonnement von Kommentaren im Blog auf der Internetseite<\/h4>\n<p>Die im Blog der shopping-club.com abgegebenen Kommentare k\u00f6nnen grunds\u00e4tzlich von Dritten abonniert werden. Insbesondere besteht die M\u00f6glichkeit, dass ein Kommentator die seinem Kommentar nachfolgenden Kommentare zu einem bestimmten Blog-Beitrag abonniert.<\/p>\n<p>Sofern sich eine betroffene Person f\u00fcr die Option entscheidet, Kommentare zu abonnieren, versendet der f\u00fcr die Verarbeitung Verantwortliche eine automatische Best\u00e4tigungsmail, um im Double-Opt-In-Verfahren zu \u00fcberpr\u00fcfen, ob sich wirklich der Inhaber der angegebenen E-Mail-Adresse f\u00fcr diese Option entschieden hat. Die Option zum Abonnement von Kommentaren kann jederzeit beendet werden.<\/p>\n<h4>8. Routinem\u00e4\u00dfige L\u00f6schung und Sperrung von personenbezogenen Daten<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche verarbeitet und speichert personenbezogene Daten der betroffenen Person nur f\u00fcr den Zeitraum, der zur Erreichung des Speicherungszwecks erforderlich ist oder sofern dies durch den Europ\u00e4ischen Richtlinien- und Verordnungsgeber oder einen anderen Gesetzgeber in Gesetzen oder Vorschriften, welchen der f\u00fcr die Verarbeitung Verantwortliche unterliegt, vorgesehen wurde.<\/p>\n<p>Entf\u00e4llt der Speicherungszweck oder l\u00e4uft eine vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber oder einem anderen zust\u00e4ndigen Gesetzgeber vorgeschriebene Speicherfrist ab, werden die personenbezogenen Daten routinem\u00e4\u00dfig und entsprechend den gesetzlichen Vorschriften gesperrt oder gel\u00f6scht.<\/p>\n<h4>9. Rechte der betroffenen Person<\/h4>\n<ul style=\"list-style: none;\">\n<li>\n<h4>a)    Recht auf Best\u00e4tigung<\/h4>\n<p>Jede betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber einger\u00e4umte Recht, von dem f\u00fcr die Verarbeitung Verantwortlichen eine Best\u00e4tigung dar\u00fcber zu verlangen, ob sie betreffende personenbezogene Daten verarbeitet werden. M\u00f6chte eine betroffene Person dieses Best\u00e4tigungsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an unseren Datenschutzbeauftragten oder einen anderen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/p>\n<\/li>\n<li>\n<h4>b)    Recht auf Auskunft<\/h4>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, jederzeit von dem f\u00fcr die Verarbeitung Verantwortlichen unentgeltliche Auskunft \u00fcber die zu seiner Person gespeicherten personenbezogenen Daten und eine Kopie dieser Auskunft zu erhalten. Ferner hat der Europ\u00e4ische Richtlinien- und Verordnungsgeber der betroffenen Person Auskunft \u00fcber folgende Informationen zugestanden:<\/p>\n<ul style=\"list-style: none;\">\n<li>die Verarbeitungszwecke<\/li>\n<li>die Kategorien personenbezogener Daten, die verarbeitet werden<\/li>\n<li>die Empf\u00e4nger oder Kategorien von Empf\u00e4ngern, gegen\u00fcber denen die personenbezogenen Daten offengelegt worden sind oder noch offengelegt werden, insbesondere bei Empf\u00e4ngern in Drittl\u00e4ndern oder bei internationalen Organisationen<\/li>\n<li>falls m\u00f6glich die geplante Dauer, f\u00fcr die die personenbezogenen Daten gespeichert werden, oder, falls dies nicht m\u00f6glich ist, die Kriterien f\u00fcr die Festlegung dieser Dauer<\/li>\n<li>das Bestehen eines Rechts auf Berichtigung oder L\u00f6schung der sie betreffenden personenbezogenen Daten oder auf Einschr\u00e4nkung der Verarbeitung durch den Verantwortlichen oder eines Widerspruchsrechts gegen diese Verarbeitung<\/li>\n<li>das Bestehen eines Beschwerderechts bei einer Aufsichtsbeh\u00f6rde<\/li>\n<li>wenn die personenbezogenen Daten nicht bei der betroffenen Person erhoben werden: Alle verf\u00fcgbaren Informationen \u00fcber die Herkunft der Daten<\/li>\n<li>das Bestehen einer automatisierten Entscheidungsfindung einschlie\u00dflich Profiling gem\u00e4\u00df Artikel 22 Abs.1 und 4 DS-GVO und \u2014 zumindest in diesen F\u00e4llen \u2014 aussagekr\u00e4ftige Informationen \u00fcber die involvierte Logik sowie die Tragweite und die angestrebten Auswirkungen einer derartigen Verarbeitung f\u00fcr die betroffene Person<\/li>\n<\/ul>\n<p>Ferner steht der betroffenen Person ein Auskunftsrecht dar\u00fcber zu, ob personenbezogene Daten an ein Drittland oder an eine internationale Organisation \u00fcbermittelt wurden. Sofern dies der Fall ist, so steht der betroffenen Person im \u00dcbrigen das Recht zu, Auskunft \u00fcber die geeigneten Garantien im Zusammenhang mit der \u00dcbermittlung zu erhalten.<\/p>\n<p>M\u00f6chte eine betroffene Person dieses Auskunftsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an unseren Datenschutzbeauftragten oder einen anderen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/p>\n<\/li>\n<li>\n<h4>c)    Recht auf Berichtigung<\/h4>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, die unverz\u00fcgliche Berichtigung sie betreffender unrichtiger personenbezogener Daten zu verlangen. Ferner steht der betroffenen Person das Recht zu, unter Ber\u00fccksichtigung der Zwecke der Verarbeitung, die Vervollst\u00e4ndigung unvollst\u00e4ndiger personenbezogener Daten \u2014 auch mittels einer erg\u00e4nzenden Erkl\u00e4rung \u2014 zu verlangen.<\/p>\n<p>M\u00f6chte eine betroffene Person dieses Berichtigungsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an unseren Datenschutzbeauftragten oder einen anderen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/p>\n<\/li>\n<li>\n<h4>d)    Recht auf L\u00f6schung (Recht auf Vergessen werden)<\/h4>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, von dem Verantwortlichen zu verlangen, dass die sie betreffenden personenbezogenen Daten unverz\u00fcglich gel\u00f6scht werden, sofern einer der folgenden Gr\u00fcnde zutrifft und soweit die Verarbeitung nicht erforderlich ist:<\/p>\n<ul style=\"list-style: none;\">\n<li>Die personenbezogenen Daten wurden f\u00fcr solche Zwecke erhoben oder auf sonstige Weise verarbeitet, f\u00fcr welche sie nicht mehr notwendig sind.<\/li>\n<li>Die betroffene Person widerruft ihre Einwilligung, auf die sich die Verarbeitung gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe a DS-GVO oder Art. 9 Abs. 2 Buchstabe a DS-GVO st\u00fctzte, und es fehlt an einer anderweitigen Rechtsgrundlage f\u00fcr die Verarbeitung.<\/li>\n<li>Die betroffene Person legt gem\u00e4\u00df Art. 21 Abs. 1 DS-GVO Widerspruch gegen die Verarbeitung ein, und es liegen keine vorrangigen berechtigten Gr\u00fcnde f\u00fcr die Verarbeitung vor, oder die betroffene Person legt gem\u00e4\u00df Art. 21 Abs. 2 DS-GVO Widerspruch gegen die Verarbeitung ein.<\/li>\n<li>Die personenbezogenen Daten wurden unrechtm\u00e4\u00dfig verarbeitet.<\/li>\n<li>Die L\u00f6schung der personenbezogenen Daten ist zur Erf\u00fcllung einer rechtlichen Verpflichtung nach dem Unionsrecht oder dem Recht der Mitgliedstaaten erforderlich, dem der Verantwortliche unterliegt.<\/li>\n<li>Die personenbezogenen Daten wurden in Bezug auf angebotene Dienste der Informationsgesellschaft gem\u00e4\u00df Art. 8 Abs. 1 DS-GVO erhoben.<\/li>\n<\/ul>\n<p>Sofern einer der oben genannten Gr\u00fcnde zutrifft und eine betroffene Person die L\u00f6schung von personenbezogenen Daten, die bei der shopping-club.com gespeichert sind, veranlassen m\u00f6chte, kann sie sich hierzu jederzeit an unseren Datenschutzbeauftragten oder einen anderen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden. Der Datenschutzbeauftragte der shopping-club.com oder ein anderer Mitarbeiter wird veranlassen, dass dem L\u00f6schverlangen unverz\u00fcglich nachgekommen wird.<\/p>\n<p>Wurden die personenbezogenen Daten von der shopping-club.com \u00f6ffentlich gemacht und ist unser Unternehmen als Verantwortlicher gem\u00e4\u00df Art. 17 Abs. 1 DS-GVO zur L\u00f6schung der personenbezogenen Daten verpflichtet, so trifft die shopping-club.com unter Ber\u00fccksichtigung der verf\u00fcgbaren Technologie und der Implementierungskosten angemessene Ma\u00dfnahmen, auch technischer Art, um andere f\u00fcr die Datenverarbeitung Verantwortliche, welche die ver\u00f6ffentlichten personenbezogenen Daten verarbeiten, dar\u00fcber in Kenntnis zu setzen, dass die betroffene Person von diesen anderen f\u00fcr die Datenverarbeitung Verantwortlichen die L\u00f6schung s\u00e4mtlicher Links zu diesen personenbezogenen Daten oder von Kopien oder Replikationen dieser personenbezogenen Daten verlangt hat, soweit die Verarbeitung nicht erforderlich ist. Der Datenschutzbeauftragte der shopping-club.com oder ein anderer Mitarbeiter wird im Einzelfall das Notwendige veranlassen.<\/p>\n<\/li>\n<li>\n<h4>e)    Recht auf Einschr\u00e4nkung der Verarbeitung<\/h4>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, von dem Verantwortlichen die Einschr\u00e4nkung der Verarbeitung zu verlangen, wenn eine der folgenden Voraussetzungen gegeben ist:<\/p>\n<ul style=\"list-style: none;\">\n<li>Die Richtigkeit der personenbezogenen Daten wird von der betroffenen Person bestritten, und zwar f\u00fcr eine Dauer, die es dem Verantwortlichen erm\u00f6glicht, die Richtigkeit der personenbezogenen Daten zu \u00fcberpr\u00fcfen.<\/li>\n<li>Die Verarbeitung ist unrechtm\u00e4\u00dfig, die betroffene Person lehnt die L\u00f6schung der personenbezogenen Daten ab und verlangt stattdessen die Einschr\u00e4nkung der Nutzung der personenbezogenen Daten.<\/li>\n<li>Der Verantwortliche ben\u00f6tigt die personenbezogenen Daten f\u00fcr die Zwecke der Verarbeitung nicht l\u00e4nger, die betroffene Person ben\u00f6tigt sie jedoch zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen.<\/li>\n<li>Die betroffene Person hat Widerspruch gegen die Verarbeitung gem. Art. 21 Abs. 1 DS-GVO eingelegt und es steht noch nicht fest, ob die berechtigten Gr\u00fcnde des Verantwortlichen gegen\u00fcber denen der betroffenen Person \u00fcberwiegen.<\/li>\n<\/ul>\n<p>Sofern eine der oben genannten Voraussetzungen gegeben ist und eine betroffene Person die Einschr\u00e4nkung von personenbezogenen Daten, die bei der shopping-club.com gespeichert sind, verlangen m\u00f6chte, kann sie sich hierzu jederzeit an unseren Datenschutzbeauftragten oder einen anderen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden. Der Datenschutzbeauftragte der shopping-club.com oder ein anderer Mitarbeiter wird die Einschr\u00e4nkung der Verarbeitung veranlassen.<\/p>\n<\/li>\n<li>\n<h4>f)     Recht auf Daten\u00fcbertragbarkeit<\/h4>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, die sie betreffenden personenbezogenen Daten, welche durch die betroffene Person einem Verantwortlichen bereitgestellt wurden, in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu erhalten. Sie hat au\u00dferdem das Recht, diese Daten einem anderen Verantwortlichen ohne Behinderung durch den Verantwortlichen, dem die personenbezogenen Daten bereitgestellt wurden, zu \u00fcbermitteln, sofern die Verarbeitung auf der Einwilligung gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe a DS-GVO oder Art. 9 Abs. 2 Buchstabe a DS-GVO oder auf einem Vertrag gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe b DS-GVO beruht und die Verarbeitung mithilfe automatisierter Verfahren erfolgt, sofern die Verarbeitung nicht f\u00fcr die Wahrnehmung einer Aufgabe erforderlich ist, die im \u00f6ffentlichen Interesse liegt oder in Aus\u00fcbung \u00f6ffentlicher Gewalt erfolgt, welche dem Verantwortlichen \u00fcbertragen wurde.<\/p>\n<p>Ferner hat die betroffene Person bei der Aus\u00fcbung ihres Rechts auf Daten\u00fcbertragbarkeit gem\u00e4\u00df Art. 20 Abs. 1 DS-GVO das Recht, zu erwirken, dass die personenbezogenen Daten direkt von einem Verantwortlichen an einen anderen Verantwortlichen \u00fcbermittelt werden, soweit dies technisch machbar ist und sofern hiervon nicht die Rechte und Freiheiten anderer Personen beeintr\u00e4chtigt werden.<\/p>\n<p>Zur Geltendmachung des Rechts auf Daten\u00fcbertragbarkeit kann sich die betroffene Person jederzeit an den von der shopping-club.com bestellten Datenschutzbeauftragten oder einen anderen Mitarbeiter wenden.<\/p>\n<\/li>\n<li>\n<h4>g)    Recht auf Widerspruch<\/h4>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, aus Gr\u00fcnden, die sich aus ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung sie betreffender personenbezogener Daten, die aufgrund von Art. 6 Abs. 1 Buchstaben e oder f DS-GVO erfolgt, Widerspruch einzulegen. Dies gilt auch f\u00fcr ein auf diese Bestimmungen gest\u00fctztes Profiling.<\/p>\n<p>Die shopping-club.com verarbeitet die personenbezogenen Daten im Falle des Widerspruchs nicht mehr, es sei denn, wir k\u00f6nnen zwingende schutzw\u00fcrdige Gr\u00fcnde f\u00fcr die Verarbeitung nachweisen, die den Interessen, Rechten und Freiheiten der betroffenen Person \u00fcberwiegen, oder die Verarbeitung dient der Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen.<\/p>\n<p>Verarbeitet die shopping-club.com personenbezogene Daten, um Direktwerbung zu betreiben, so hat die betroffene Person das Recht, jederzeit Widerspruch gegen die Verarbeitung der personenbezogenen Daten zum Zwecke derartiger Werbung einzulegen. Dies gilt auch f\u00fcr das Profiling, soweit es mit solcher Direktwerbung in Verbindung steht. Widerspricht die betroffene Person gegen\u00fcber der shopping-club.com der Verarbeitung f\u00fcr Zwecke der Direktwerbung, so wird die shopping-club.com die personenbezogenen Daten nicht mehr f\u00fcr diese Zwecke verarbeiten.<\/p>\n<p>Zudem hat die betroffene Person das Recht, aus Gr\u00fcnden, die sich aus ihrer besonderen Situation ergeben, gegen die sie betreffende Verarbeitung personenbezogener Daten, die bei der shopping-club.com zu wissenschaftlichen oder historischen Forschungszwecken oder zu statistischen Zwecken gem\u00e4\u00df Art. 89 Abs. 1 DS-GVO erfolgen, Widerspruch einzulegen, es sei denn, eine solche Verarbeitung ist zur Erf\u00fcllung einer im \u00f6ffentlichen Interesse liegenden Aufgabe erforderlich.<\/p>\n<p>Zur Aus\u00fcbung des Rechts auf Widerspruch kann sich die betroffene Person direkt an den Datenschutzbeauftragten der shopping-club.com oder einen anderen Mitarbeiter wenden. Der betroffenen Person steht es ferner frei, im Zusammenhang mit der Nutzung von Diensten der Informationsgesellschaft, ungeachtet der Richtlinie 2002\/58\/EG, ihr Widerspruchsrecht mittels automatisierter Verfahren auszu\u00fcben, bei denen technische Spezifikationen verwendet werden.<\/p>\n<\/li>\n<li>\n<h4>h)    Automatisierte Entscheidungen im Einzelfall einschlie\u00dflich Profiling<\/h4>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, nicht einer ausschlie\u00dflich auf einer automatisierten Verarbeitung \u2014 einschlie\u00dflich Profiling \u2014 beruhenden Entscheidung unterworfen zu werden, die ihr gegen\u00fcber rechtliche Wirkung entfaltet oder sie in \u00e4hnlicher Weise erheblich beeintr\u00e4chtigt, sofern die Entscheidung (1) nicht f\u00fcr den Abschluss oder die Erf\u00fcllung eines Vertrags zwischen der betroffenen Person und dem Verantwortlichen erforderlich ist, oder (2) aufgrund von Rechtsvorschriften der Union oder der Mitgliedstaaten, denen der Verantwortliche unterliegt, zul\u00e4ssig ist und diese Rechtsvorschriften angemessene Ma\u00dfnahmen zur Wahrung der Rechte und Freiheiten sowie der berechtigten Interessen der betroffenen Person enthalten oder (3) mit ausdr\u00fccklicher Einwilligung der betroffenen Person erfolgt.<\/p>\n<p>Ist die Entscheidung (1) f\u00fcr den Abschluss oder die Erf\u00fcllung eines Vertrags zwischen der betroffenen Person und dem Verantwortlichen erforderlich oder (2) erfolgt sie mit ausdr\u00fccklicher Einwilligung der betroffenen Person, trifft die shopping-club.com angemessene Ma\u00dfnahmen, um die Rechte und Freiheiten sowie die berechtigten Interessen der betroffenen Person zu wahren, wozu mindestens das Recht auf Erwirkung des Eingreifens einer Person seitens des Verantwortlichen, auf Darlegung des eigenen Standpunkts und auf Anfechtung der Entscheidung geh\u00f6rt.<\/p>\n<p>M\u00f6chte die betroffene Person Rechte mit Bezug auf automatisierte Entscheidungen geltend machen, kann sie sich hierzu jederzeit an unseren Datenschutzbeauftragten oder einen anderen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/p>\n<\/li>\n<li>\n<h4>i)      Recht auf Widerruf einer datenschutzrechtlichen Einwilligung<\/h4>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, eine Einwilligung zur Verarbeitung personenbezogener Daten jederzeit zu widerrufen.<\/p>\n<p>M\u00f6chte die betroffene Person ihr Recht auf Widerruf einer Einwilligung geltend machen, kann sie sich hierzu jederzeit an unseren Datenschutzbeauftragten oder einen anderen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/p>\n<\/li>\n<\/ul>\n<h4>10. Datenschutz bei Bewerbungen und im Bewerbungsverfahren<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche erhebt und verarbeitet die personenbezogenen Daten von Bewerbern zum Zwecke der Abwicklung des Bewerbungsverfahrens. Die Verarbeitung kann auch auf elektronischem Wege erfolgen. Dies ist insbesondere dann der Fall, wenn ein Bewerber entsprechende Bewerbungsunterlagen auf dem elektronischen Wege, beispielsweise per E-Mail oder \u00fcber ein auf der Internetseite befindliches Webformular, an den f\u00fcr die Verarbeitung Verantwortlichen \u00fcbermittelt. Schlie\u00dft der f\u00fcr die Verarbeitung Verantwortliche einen Anstellungsvertrag mit einem Bewerber, werden die \u00fcbermittelten Daten zum Zwecke der Abwicklung des Besch\u00e4ftigungsverh\u00e4ltnisses unter Beachtung der gesetzlichen Vorschriften gespeichert. Wird von dem f\u00fcr die Verarbeitung Verantwortlichen kein Anstellungsvertrag mit dem Bewerber geschlossen, so werden die Bewerbungsunterlagen zwei Monate nach Bekanntgabe der Absageentscheidung automatisch gel\u00f6scht, sofern einer L\u00f6schung keine sonstigen berechtigten Interessen des f\u00fcr die Verarbeitung Verantwortlichen entgegenstehen. Sonstiges berechtigtes Interesse in diesem Sinne ist beispielsweise eine Beweispflicht in einem Verfahren nach dem Allgemeinen Gleichbehandlungsgesetz (AGG).<\/p>\n<h4>11. Datenschutzbestimmungen zu Einsatz und Verwendung von affilinet<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten des Unternehmens affilinet integriert. Affilinet ist ein deutsches Affiliate-Netzwerk, welches Affiliate-Marketing anbietet.<\/p>\n<p>Affiliate-Marketing ist eine Internetgest\u00fctzte Vertriebsform, die es kommerziellen Betreibern von Internetseiten, den sogenannten Merchants oder Advertisern, erm\u00f6glicht, Werbung, die meist \u00fcber Klick- oder Sale-Provisionen verg\u00fctet wird, auf Internetseiten Dritter, also bei Vertriebspartnern, die auch Affiliates oder Publisher genannt werden, einzublenden. Der Merchant stellt \u00fcber das Affiliate-Netzwerk ein Werbemittel, also einen Werbebanner oder andere geeignete Mittel der Internetwerbung, zur Verf\u00fcgung, welche in der Folge von einem Affiliate auf eigenen Internetseiten eingebunden oder \u00fcber sonstige Kan\u00e4le, wie etwa das Keyword-Advertising oder E-Mail-Marketing, beworben werden.<\/p>\n<p>Betreibergesellschaft von Affilinet ist die affilinet GmbH, Sapporobogen 6-8, 80637 M\u00fcnchen, Deutschland.<\/p>\n<p>Affilinet setzt ein Cookie auf dem informationstechnologischen System der betroffenen Person. Was Cookies sind, wurde oben bereits erl\u00e4utert. Das Tracking-Cookie von Affilinet speichert keinerlei personenbezogene Daten. Gespeichert werden lediglich die Identifikationsnummer des Affiliate, also des den potentiellen Kunden vermittelnden Partners, sowie die Ordnungsnummer des Besuchers einer Internetseite und des angeklickten Werbemittels. Zweck der Speicherung dieser Daten ist die Abwicklung von Provisionszahlungen zwischen einem Merchant und dem Affiliate, welche \u00fcber das Affiliate-Netzwerk, also Affilinet, abgewickelt werden.<\/p>\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass Affilinet ein Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem k\u00f6nnen von Affilinet bereits gesetzte Cookies jederzeit \u00fcber einen Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.<\/p>\n<p>Die geltenden Datenschutzbestimmungen von Affilinet k\u00f6nnen unter https:\/\/www.affili.net\/de\/footeritem\/datenschutz abgerufen werden.<\/p>\n<h4>12. Datenschutzbestimmungen zu Einsatz und Verwendung von Facebook<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten des Unternehmens Facebook integriert. Facebook ist ein soziales Netzwerk.<\/p>\n<p>Ein soziales Netzwerk ist ein im Internet betriebener sozialer Treffpunkt, eine Online-Gemeinschaft, die es den Nutzern in der Regel erm\u00f6glicht, untereinander zu kommunizieren und im virtuellen Raum zu interagieren. Ein soziales Netzwerk kann als Plattform zum Austausch von Meinungen und Erfahrungen dienen oder erm\u00f6glicht es der Internetgemeinschaft, pers\u00f6nliche oder unternehmensbezogene Informationen bereitzustellen. Facebook erm\u00f6glicht den Nutzern des sozialen Netzwerkes unter anderem die Erstellung von privaten Profilen, den Upload von Fotos und eine Vernetzung \u00fcber Freundschaftsanfragen.<\/p>\n<p>Betreibergesellschaft von Facebook ist die Facebook, Inc., 1 Hacker Way, Menlo Park, CA 94025, USA. F\u00fcr die Verarbeitung personenbezogener Daten Verantwortlicher ist, wenn eine betroffene Person au\u00dferhalb der USA oder Kanada lebt, die Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Ireland.<\/p>\n<p>Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Facebook-Komponente (Facebook-Plug-In) integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Facebook-Komponente veranlasst, eine Darstellung der entsprechenden Facebook-Komponente von Facebook herunterzuladen. Eine Gesamt\u00fcbersicht \u00fcber alle Facebook-Plug-Ins kann unter https:\/\/developers.facebook.com\/docs\/plugins\/?locale=de_DE abgerufen werden. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Facebook Kenntnis dar\u00fcber, welche konkrete Unterseite unserer Internetseite durch die betroffene Person besucht wird.<\/p>\n<p>Sofern die betroffene Person gleichzeitig bei Facebook eingeloggt ist, erkennt Facebook mit jedem Aufruf unserer Internetseite durch die betroffene Person und w\u00e4hrend der gesamten Dauer des jeweiligen Aufenthaltes auf unserer Internetseite, welche konkrete Unterseite unserer Internetseite die betroffene Person besucht. Diese Informationen werden durch die Facebook-Komponente gesammelt und durch Facebook dem jeweiligen Facebook-Account der betroffenen Person zugeordnet. Bet\u00e4tigt die betroffene Person einen der auf unserer Internetseite integrierten Facebook-Buttons, beispielsweise den \u201eGef\u00e4llt mir\u201c-Button, oder gibt die betroffene Person einen Kommentar ab, ordnet Facebook diese Information dem pers\u00f6nlichen Facebook-Benutzerkonto der betroffenen Person zu und speichert diese personenbezogenen Daten.<\/p>\n<p>Facebook erh\u00e4lt \u00fcber die Facebook-Komponente immer dann eine Information dar\u00fcber, dass die betroffene Person unsere Internetseite besucht hat, wenn die betroffene Person zum Zeitpunkt des Aufrufs unserer Internetseite gleichzeitig bei Facebook eingeloggt ist; dies findet unabh\u00e4ngig davon statt, ob die betroffene Person die Facebook-Komponente anklickt oder nicht. Ist eine derartige \u00dcbermittlung dieser Informationen an Facebook von der betroffenen Person nicht gewollt, kann diese die \u00dcbermittlung dadurch verhindern, dass sie sich vor einem Aufruf unserer Internetseite aus ihrem Facebook-Account ausloggt.<\/p>\n<p>Die von Facebook ver\u00f6ffentlichte Datenrichtlinie, die unter https:\/\/de-de.facebook.com\/about\/privacy\/ abrufbar ist, gibt Aufschluss \u00fcber die Erhebung, Verarbeitung und Nutzung personenbezogener Daten durch Facebook. Ferner wird dort erl\u00e4utert, welche Einstellungsm\u00f6glichkeiten Facebook zum Schutz der Privatsph\u00e4re der betroffenen Person bietet. Zudem sind unterschiedliche Applikationen erh\u00e4ltlich, die es erm\u00f6glichen, eine Daten\u00fcbermittlung an Facebook zu unterdr\u00fccken. Solche Applikationen k\u00f6nnen durch die betroffene Person genutzt werden, um eine Daten\u00fcbermittlung an Facebook zu unterdr\u00fccken.<\/p>\n<h4>13. Datenschutzbestimmungen zu Einsatz und Verwendung von Funktionen des Amazon-Partnerprogramms<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat als Teilnehmer des Amazon-Partnerprogramms auf dieser Internetseite Amazon-Komponenten integriert. Die Amazon-Komponenten wurden von Amazon mit dem Ziel konzipiert, Kunden \u00fcber Werbeanzeigen auf unterschiedliche Internetseiten der Amazon-Gruppe, insbesondere auf Amazon.co.uk, Local.Amazon.co.uk, Amazon.de, BuyVIP.com, Amazon.fr, Amazon.it und Amazon.es. BuyVIP.com gegen Zahlung einer Provision zu vermitteln. Der f\u00fcr die Verarbeitung Verantwortliche kann durch die Nutzung der Amazon-Komponenten Werbeeinnahmen generieren.<\/p>\n<p>Betreibergesellschaft dieser Amazon-Komponenten ist die Amazon EU S.\u00e0.r.l, 5 Rue Plaetis, L-2338 Luxembourg, Luxemburg.<\/p>\n<p>Amazon setzt ein Cookie auf dem informationstechnologischen System der betroffenen Person. Was Cookies sind, wurde oben bereits erl\u00e4utert. Durch jeden einzelnen Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Amazon-Komponente integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Amazon-Komponente veranlasst, Daten zum Zwecke der Online-Werbung und der Abrechnung von Provisionen an Amazon zu \u00fcbermitteln. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Amazon Kenntnis \u00fcber personenbezogene Daten, die Amazon dazu dienen, die Herkunft von bei Amazon eingehenden Bestellungen nachzuvollziehen und in der Folge eine Provisionsabrechnung zu erm\u00f6glichen. Amazon kann unter anderem nachvollziehen, dass die betroffene Person einen Partnerlink auf unserer Internetseite angeklickt hat.<\/p>\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass Amazon ein Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem k\u00f6nnen von Amazon bereits gesetzte Cookies jederzeit \u00fcber einen Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.<\/p>\n<p>Weitere Informationen und die geltenden Datenschutzbestimmungen von Amazon k\u00f6nnen unter https:\/\/www.amazon.de\/gp\/help\/customer\/display.html?nodeId=3312401 abgerufen werden.<\/p>\n<h4>14. Datenschutzbestimmungen zu Einsatz und Verwendung von Google AdSense<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Google AdSense integriert. Google AdSense ist ein Online-Dienst, \u00fcber welchen eine Vermittlung von Werbung auf Drittseiten erm\u00f6glicht wird. Google AdSense beruht auf einem Algorithmus, welcher die auf Drittseiten angezeigten Werbeanzeigen passend zu den Inhalten der jeweiligen Drittseite ausw\u00e4hlt. Google AdSense gestattet ein interessenbezogenes Targeting des Internetnutzers, welches mittels Generierung von individuellen Benutzerprofilen umgesetzt wird.<\/p>\n<p>Betreibergesellschaft der Google-AdSense-Komponente ist die Alphabet Inc., 1600 Amphitheatre Pkwy, Mountain View, CA 94043-1351, USA.<\/p>\n<p>Der Zweck der Google-AdSense-Komponente ist die Einbindung von Werbeanzeigen auf unserer Internetseite. Google-AdSense setzt ein Cookie auf dem informationstechnologischen System der betroffenen Person. Was Cookies sind, wurde oben bereits erl\u00e4utert. Mit der Setzung des Cookies wird der Alphabet Inc. eine Analyse der Benutzung unserer Internetseite erm\u00f6glicht. Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Google-AdSense-Komponente integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Google-AdSense-Komponente veranlasst, Daten zum Zwecke der Online-Werbung und der Abrechnung von Provisionen an die Alphabet Inc. zu \u00fcbermitteln. Im Rahmen dieses technischen Verfahrens erh\u00e4lt die Alphabet Inc. Kenntnis \u00fcber personenbezogene Daten, wie der IP-Adresse der betroffenen Person, die der Alphabet Inc. unter anderem dazu dienen, die Herkunft der Besucher und Klicks nachzuvollziehen und in der Folge Provisionsabrechnungen zu erm\u00f6glichen.<\/p>\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass die Alphabet Inc. ein Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem kann ein von der Alphabet Inc. bereits gesetzter Cookie jederzeit \u00fcber den Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.<\/p>\n<p>Google AdSense verwendet zudem sogenannte Z\u00e4hlpixel. Ein Z\u00e4hlpixel ist eine Miniaturgrafik, die in Internetseiten eingebettet wird, um eine Logdatei-Aufzeichnung und eine Logdatei-Analyse zu erm\u00f6glichen, wodurch eine statistische Auswertung durchgef\u00fchrt werden kann. Anhand des eingebetteten Z\u00e4hlpixels kann die Alphabet Inc. erkennen, ob und wann eine Internetseite von einer betroffenen Person ge\u00f6ffnet wurde und welche Links von der betroffenen Person angeklickt wurden. Z\u00e4hlpixel dienen unter anderem dazu, den Besucherfluss einer Internetseite auszuwerten.<\/p>\n<p>\u00dcber Google AdSense werden personenbezogene Daten und Informationen, was auch die IP-Adresse umfasst und zur Erfassung und Abrechnung der angezeigten Werbeanzeigen notwendig ist, an die Alphabet Inc. in die Vereinigten Staaten von Amerika \u00fcbertragen. Diese personenbezogenen Daten werden in den Vereinigten Staaten von Amerika gespeichert und verarbeitet. Die Alphabet Inc. gibt diese \u00fcber das technische Verfahren erhobenen personenbezogenen Daten unter Umst\u00e4nden an Dritte weiter.<\/p>\n<p>Google-AdSense wird unter diesem Link https:\/\/www.google.de\/intl\/de\/adsense\/start\/ genauer erl\u00e4utert.<\/p>\n<h4>15. Datenschutzbestimmungen zu Einsatz und Verwendung von Google Analytics (mit Anonymisierungsfunktion)<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite die Komponente Google Analytics (mit Anonymisierungsfunktion) integriert. Google Analytics ist ein Web-Analyse-Dienst. Web-Analyse ist die Erhebung, Sammlung und Auswertung von Daten \u00fcber das Verhalten von Besuchern von Internetseiten. Ein Web-Analyse-Dienst erfasst unter anderem Daten dar\u00fcber, von welcher Internetseite eine betroffene Person auf eine Internetseite gekommen ist (sogenannte Referrer), auf welche Unterseiten der Internetseite zugegriffen oder wie oft und f\u00fcr welche Verweildauer eine Unterseite betrachtet wurde. Eine Web-Analyse wird \u00fcberwiegend zur Optimierung einer Internetseite und zur Kosten-Nutzen-Analyse von Internetwerbung eingesetzt.<\/p>\n<p>Betreibergesellschaft der Google-Analytics-Komponente ist die Google Inc., 1600 Amphitheatre Pkwy, Mountain View, CA 94043-1351, USA.<\/p>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche verwendet f\u00fcr die Web-Analyse \u00fcber Google Analytics den Zusatz &#8222;_gat._anonymizeIp&#8220;. Mittels dieses Zusatzes wird die IP-Adresse des Internetanschlusses der betroffenen Person von Google gek\u00fcrzt und anonymisiert, wenn der Zugriff auf unsere Internetseiten aus einem Mitgliedstaat der Europ\u00e4ischen Union oder aus einem anderen Vertragsstaat des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum erfolgt.<\/p>\n<p>Der Zweck der Google-Analytics-Komponente ist die Analyse der Besucherstr\u00f6me auf unserer Internetseite. Google nutzt die gewonnenen Daten und Informationen unter anderem dazu, die Nutzung unserer Internetseite auszuwerten, um f\u00fcr uns Online-Reports, welche die Aktivit\u00e4ten auf unseren Internetseiten aufzeigen, zusammenzustellen, und um weitere mit der Nutzung unserer Internetseite in Verbindung stehende Dienstleistungen zu erbringen.<\/p>\n<p>Google Analytics setzt ein Cookie auf dem informationstechnologischen System der betroffenen Person. Was Cookies sind, wurde oben bereits erl\u00e4utert. Mit Setzung des Cookies wird Google eine Analyse der Benutzung unserer Internetseite erm\u00f6glicht. Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Google-Analytics-Komponente integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Google-Analytics-Komponente veranlasst, Daten zum Zwecke der Online-Analyse an Google zu \u00fcbermitteln. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Google Kenntnis \u00fcber personenbezogene Daten, wie der IP-Adresse der betroffenen Person, die Google unter anderem dazu dienen, die Herkunft der Besucher und Klicks nachzuvollziehen und in der Folge Provisionsabrechnungen zu erm\u00f6glichen.<\/p>\n<p>Mittels des Cookies werden personenbezogene Informationen, beispielsweise die Zugriffszeit, der Ort, von welchem ein Zugriff ausging und die H\u00e4ufigkeit der Besuche unserer Internetseite durch die betroffene Person, gespeichert. Bei jedem Besuch unserer Internetseiten werden diese personenbezogenen Daten, einschlie\u00dflich der IP-Adresse des von der betroffenen Person genutzten Internetanschlusses, an Google in den Vereinigten Staaten von Amerika \u00fcbertragen. Diese personenbezogenen Daten werden durch Google in den Vereinigten Staaten von Amerika gespeichert. Google gibt diese \u00fcber das technische Verfahren erhobenen personenbezogenen Daten unter Umst\u00e4nden an Dritte weiter.<\/p>\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass Google ein Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem kann ein von Google Analytics bereits gesetzter Cookie jederzeit \u00fcber den Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.<\/p>\n<p>Ferner besteht f\u00fcr die betroffene Person die M\u00f6glichkeit, einer Erfassung der durch Google Analytics erzeugten, auf eine Nutzung dieser Internetseite bezogenen Daten sowie der Verarbeitung dieser Daten durch Google zu widersprechen und eine solche zu verhindern. Hierzu muss die betroffene Person ein Browser-Add-On unter dem Link https:\/\/tools.google.com\/dlpage\/gaoptout herunterladen und installieren. Dieses Browser-Add-On teilt Google Analytics \u00fcber JavaScript mit, dass keine Daten und Informationen zu den Besuchen von Internetseiten an Google Analytics \u00fcbermittelt werden d\u00fcrfen. Die Installation des Browser-Add-Ons wird von Google als Widerspruch gewertet. Wird das informationstechnologische System der betroffenen Person zu einem sp\u00e4teren Zeitpunkt gel\u00f6scht, formatiert oder neu installiert, muss durch die betroffene Person eine erneute Installation des Browser-Add-Ons erfolgen, um Google Analytics zu deaktivieren. Sofern das Browser-Add-On durch die betroffene Person oder einer anderen Person, die ihrem Machtbereich zuzurechnen ist, deinstalliert oder deaktiviert wird, besteht die M\u00f6glichkeit der Neuinstallation oder der erneuten Aktivierung des Browser-Add-Ons.<\/p>\n<p>Weitere Informationen und die geltenden Datenschutzbestimmungen von Google k\u00f6nnen unter https:\/\/www.google.de\/intl\/de\/policies\/privacy\/ und unter http:\/\/www.google.com\/analytics\/terms\/de.html abgerufen werden. Google Analytics wird unter diesem Link https:\/\/www.google.com\/intl\/de_de\/analytics\/ genauer erl\u00e4utert.<\/p>\n<h4>16. Datenschutzbestimmungen zu Einsatz und Verwendung von Google+<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite als Komponente die Google+ Schaltfl\u00e4che integriert. Google+ ist ein sogenanntes soziales Netzwerk. Ein soziales Netzwerk ist ein im Internet betriebener sozialer Treffpunkt, eine Online-Gemeinschaft, die es den Nutzern in der Regel erm\u00f6glicht, untereinander zu kommunizieren und im virtuellen Raum zu interagieren. Ein soziales Netzwerk kann als Plattform zum Austausch von Meinungen und Erfahrungen dienen oder erm\u00f6glicht es der Internetgemeinschaft, pers\u00f6nliche oder unternehmensbezogene Informationen bereitzustellen. Google+ erm\u00f6glicht den Nutzern des sozialen Netzwerkes unter anderem die Erstellung von privaten Profilen, den Upload von Fotos und eine Vernetzung \u00fcber Freundschaftsanfragen.<\/p>\n<p>Betreibergesellschaft von Google+ ist die Google Inc., 1600 Amphitheatre Pkwy, Mountain View, CA 94043-1351, USA.<\/p>\n<p>Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Google+ Schaltfl\u00e4che integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Google+ Schaltfl\u00e4che veranlasst, eine Darstellung der entsprechenden Google+ Schaltfl\u00e4che von Google herunterzuladen. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Google Kenntnis dar\u00fcber, welche konkrete Unterseite unserer Internetseite durch die betroffene Person besucht wird. Genauere Informationen zu Google+ sind unter https:\/\/developers.google.com\/+\/ abrufbar.<\/p>\n<p>Sofern die betroffene Person gleichzeitig bei Google+ eingeloggt ist, erkennt Google mit jedem Aufruf unserer Internetseite durch die betroffene Person und w\u00e4hrend der gesamten Dauer des jeweiligen Aufenthaltes auf unserer Internetseite, welche konkrete Unterseite unserer Internetseite die betroffene Person besucht. Diese Informationen werden durch die Google+ Schaltfl\u00e4che gesammelt und durch Google dem jeweiligen Google+-Account der betroffenen Person zugeordnet.<\/p>\n<p>Bet\u00e4tigt die betroffene Person einen der auf unserer Internetseite integrierten Google+-Buttons und gibt damit eine Google+1 Empfehlung ab, ordnet Google diese Information dem pers\u00f6nlichen Google+-Benutzerkonto der betroffenen Person zu und speichert diese personenbezogenen Daten. Google speichert die Google+1-Empfehlung der betroffenen Person und macht diese in \u00dcbereinstimmung mit den von der betroffenen Person diesbez\u00fcglich akzeptierten Bedingungen \u00f6ffentlich zug\u00e4nglich. Eine von der betroffenen Person auf dieser Internetseite abgegebene Google+1-Empfehlung wird in der Folge zusammen mit anderen personenbezogenen Daten, wie dem Namen des von der betroffenen Person genutzten Google+1-Accounts und dem in diesem hinterlegten Foto in anderen Google-Diensten, beispielsweise den Suchmaschinenergebnissen der Google-Suchmaschine, dem Google-Konto der betroffenen Person oder an sonstigen Stellen, beispielsweise auf Internetseiten oder im Zusammenhang mit Werbeanzeigen, gespeichert und verarbeitet. Ferner ist Google in der Lage, den Besuch auf dieser Internetseite mit anderen bei Google gespeicherten personenbezogenen Daten zu verkn\u00fcpfen. Google zeichnet diese personenbezogenen Informationen ferner mit dem Zweck auf, die unterschiedlichen Dienste von Google zu verbessern oder zu optimieren.<\/p>\n<p>Google erh\u00e4lt \u00fcber die Google+-Schaltfl\u00e4che immer dann eine Information dar\u00fcber, dass die betroffene Person unsere Internetseite besucht hat, wenn die betroffene Person zum Zeitpunkt des Aufrufs unserer Internetseite gleichzeitig bei Google+ eingeloggt ist; dies findet unabh\u00e4ngig davon statt, ob die betroffene Person die Google+-Schaltfl\u00e4che anklickt oder nicht.<\/p>\n<p>Ist eine \u00dcbermittlung personenbezogener Daten an Google von der betroffenen Person nicht gewollt, kann diese eine solche \u00dcbermittlung dadurch verhindern, dass sie sich vor einem Aufruf unserer Internetseite aus ihrem Google+-Account ausloggt.<\/p>\n<p>Weitere Informationen und die geltenden Datenschutzbestimmungen von Google k\u00f6nnen unter https:\/\/www.google.de\/intl\/de\/policies\/privacy\/ abgerufen werden. Weitere Hinweise von Google zur Google+1-Schaltfl\u00e4che k\u00f6nnen unter https:\/\/developers.google.com\/+\/web\/buttons-policy abgerufen werden.<\/p>\n<h4>17. Datenschutzbestimmungen zu Einsatz und Verwendung von Instagram<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten des Dienstes Instagram integriert. Instagram ist ein Dienst, der als audiovisuelle Plattform zu qualifizieren ist und den Nutzern das Teilen von Fotos und Videos und zudem eine Weiterverbreitung solcher Daten in anderen sozialen Netzwerken erm\u00f6glicht.<\/p>\n<p>Betreibergesellschaft der Dienste von Instagram ist die Instagram LLC, 1 Hacker Way, Building 14 First Floor, Menlo Park, CA, USA.<\/p>\n<p>Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Instagram-Komponente (Insta-Button) integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Instagram-Komponente veranlasst, eine Darstellung der entsprechenden Komponente von Instagram herunterzuladen. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Instagram Kenntnis dar\u00fcber, welche konkrete Unterseite unserer Internetseite durch die betroffene Person besucht wird.<\/p>\n<p>Sofern die betroffene Person gleichzeitig bei Instagram eingeloggt ist, erkennt Instagram mit jedem Aufruf unserer Internetseite durch die betroffene Person und w\u00e4hrend der gesamten Dauer des jeweiligen Aufenthaltes auf unserer Internetseite, welche konkrete Unterseite die betroffene Person besucht. Diese Informationen werden durch die Instagram-Komponente gesammelt und durch Instagram dem jeweiligen Instagram-Account der betroffenen Person zugeordnet. Bet\u00e4tigt die betroffene Person einen der auf unserer Internetseite integrierten Instagram-Buttons, werden die damit \u00fcbertragenen Daten und Informationen dem pers\u00f6nlichen Instagram-Benutzerkonto der betroffenen Person zugeordnet und von Instagram gespeichert und verarbeitet.<\/p>\n<p>Instagram erh\u00e4lt \u00fcber die Instagram-Komponente immer dann eine Information dar\u00fcber, dass die betroffene Person unsere Internetseite besucht hat, wenn die betroffene Person zum Zeitpunkt des Aufrufs unserer Internetseite gleichzeitig bei Instagram eingeloggt ist; dies findet unabh\u00e4ngig davon statt, ob die betroffene Person die Instagram-Komponente anklickt oder nicht. Ist eine derartige \u00dcbermittlung dieser Informationen an Instagram von der betroffenen Person nicht gewollt, kann diese die \u00dcbermittlung dadurch verhindern, dass sie sich vor einem Aufruf unserer Internetseite aus ihrem Instagram-Account ausloggt.<\/p>\n<p>Weitere Informationen und die geltenden Datenschutzbestimmungen von Instagram k\u00f6nnen unter https:\/\/help.instagram.com\/155833707900388 und https:\/\/www.instagram.com\/about\/legal\/privacy\/ abgerufen werden.<\/p>\n<h4>18. Datenschutzbestimmungen zu Einsatz und Verwendung von Jetpack f\u00fcr WordPress<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Jetpack integriert. Jetpack ist ein WordPress-Plug-In, welches dem Betreiber einer Internetseite, die auf WordPress aufbaut, zus\u00e4tzliche Funktionen bietet. Jetpack gestattet dem Internetseitenbetreiber unter anderem eine \u00dcbersicht \u00fcber die Besucher der Seite. Durch die Anzeige von verwandten Beitr\u00e4gen und Publikationen oder die M\u00f6glichkeit, Inhalte auf der Seite zu teilen, ist ferner die Steigerung der Besucherzahlen m\u00f6glich. Au\u00dferdem sind Sicherheitsfunktionen in Jetpack integriert, sodass eine Jetpack nutzende Internetseite besser gegen Brute-Force-Attacken gesch\u00fctzt ist. Jetpack optimiert und beschleunigt ferner das Laden der auf der Internetseite integrierten Bilder.<\/p>\n<p>Betreibergesellschaft des Jetpack-Plug-Ins f\u00fcr WordPress ist die Automattic Inc., 132 Hawthorne Street, San Francisco, CA 94107, USA. Die Betreibergesellschaft setzt die Trackingtechnologie der Quantcast Inc., 201 Third Street, San Francisco, CA 94103, USA, ein.<\/p>\n<p>Jetpack setzt ein Cookie auf dem informationstechnologischen System der betroffenen Person. Was Cookies sind, wurde oben bereits erl\u00e4utert. Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Jetpack-Komponente integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Jetpack-Komponente veranlasst, Daten zur Analysezwecken an Automattic zu \u00fcbermitteln. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Automattic Kenntnis \u00fcber Daten, die in der Folge zur Erstellung einer \u00dcbersicht der Internetseiten-Besuche verwendet werden. Die so gewonnenen Daten dienen der Analyse des Verhaltens der betroffenen Person, welche auf die Internetseite des f\u00fcr die Verarbeitung Verantwortlichen zugegriffen hat und werden mit dem Ziel, die Internetseite zu optimieren, ausgewertet. Die \u00fcber die Jetpack-Komponente erhobenen Daten werden nicht ohne eine vorherige Einholung einer gesonderten ausdr\u00fccklichen Einwilligung der betroffenen Person dazu genutzt, die betroffene Person zu identifizieren. Die Daten gelangen ferner Quantcast zur Kenntnis. Quantcast nutzt die Daten zu den gleichen Zwecken wie Automattic.<\/p>\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass Automattic\/Quantcast ein Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem k\u00f6nnen von Automattic bereits gesetzte Cookies jederzeit \u00fcber den Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.<\/p>\n<p>Ferner besteht f\u00fcr die betroffene Person die M\u00f6glichkeit, einer Erfassung der durch das Jetpack-Cookie erzeugten, auf eine Nutzung dieser Internetseite bezogenen Daten sowie der Verarbeitung dieser Daten durch Automattic\/Quantcast zu widersprechen und eine solche zu verhindern. Hierzu muss die betroffene Person den Opt-Out-Button unter dem Link https:\/\/www.quantcast.com\/opt-out\/ dr\u00fccken, der einen Opt-Out-Cookie setzt. Der mit dem Widerspruch gesetzte Opt-Out-Cookie wird auf dem von der betroffenen Person genutzten informationstechnologischen System abgelegt. Werden die Cookies auf dem System der betroffenen Person nach einem Widerspruch gel\u00f6scht, muss die betroffene Person den Link erneut aufrufen und einen neuen Opt-Out-Cookie setzen.<\/p>\n<p>Mit der Setzung des Opt-Out-Cookies besteht jedoch die M\u00f6glichkeit, dass die Internetseiten des f\u00fcr die Verarbeitung Verantwortlichen f\u00fcr die betroffene Person nicht mehr vollumf\u00e4nglich nutzbar sind.<\/p>\n<p>Die geltenden Datenschutzbestimmungen von Automattic sind unter https:\/\/automattic.com\/privacy\/ abrufbar. Die geltenden Datenschutzbestimmungen von Quantcast sind unter https:\/\/www.quantcast.com\/privacy\/ abrufbar.<\/p>\n<h4>19. Datenschutzbestimmungen zu Einsatz und Verwendung von Pinterest<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten der Pinterest Inc. integriert. Pinterest ist ein sogenanntes soziales Netzwerk. Ein soziales Netzwerk ist ein im Internet betriebener sozialer Treffpunkt, eine Online-Gemeinschaft, die es den Nutzern in der Regel erm\u00f6glicht, untereinander zu kommunizieren und im virtuellen Raum zu interagieren. Ein soziales Netzwerk kann als Plattform zum Austausch von Meinungen und Erfahrungen dienen oder erm\u00f6glicht es der Internetgemeinschaft, pers\u00f6nliche oder unternehmensbezogene Informationen bereitzustellen. Pinterest erm\u00f6glicht den Nutzern des sozialen Netzwerkes unter anderem, Bilderkollektionen und Einzelbilder sowie Beschreibungen an virtuellen Pinnw\u00e4nden zu ver\u00f6ffentlichen (sogenanntes pinnen), welche dann wiederum von anderen Nutzern geteilt (sogenanntes repinnen) oder kommentiert werden k\u00f6nnen.<\/p>\n<p>Betreibergesellschaft von Pinterest ist die Pinterest Inc., 808 Brannan Street, San Francisco, CA 94103, USA.<\/p>\n<p>Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Pinterest-Komponente (Pinterest-Plug-In) integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Pinterest-Komponente veranlasst, eine Darstellung der entsprechenden Pinterest-Komponente von Pinterest herunterzuladen. Mehr Informationen zu Pinterest sind unter https:\/\/pinterest.com\/ abrufbar. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Pinterest Kenntnis dar\u00fcber, welche konkrete Unterseite unserer Internetseite durch die betroffene Person besucht wird.<\/p>\n<p>Sofern die betroffene Person gleichzeitig bei Pinterest eingeloggt ist, erkennt Pinterest mit jedem Aufruf unserer Internetseite durch die betroffene Person und w\u00e4hrend der gesamten Dauer des jeweiligen Aufenthaltes auf unserer Internetseite, welche konkrete Unterseite unserer Internetseite die betroffene Person besucht. Diese Informationen werden durch die Pinterest-Komponente gesammelt und durch Pinterest dem jeweiligen Pinterest-Account der betroffenen Person zugeordnet. Bet\u00e4tigt die betroffene Person einen auf unserer Internetseite integrierten Pinterest-Button, ordnet Pinterest diese Information dem pers\u00f6nlichen Pinterest-Benutzerkonto der betroffenen Person zu und speichert diese personenbezogenen Daten.<\/p>\n<p>Pinterest erh\u00e4lt \u00fcber die Pinterest-Komponente immer dann eine Information dar\u00fcber, dass die betroffene Person unsere Internetseite besucht hat, wenn die betroffene Person zum Zeitpunkt des Aufrufs unserer Internetseite gleichzeitig bei Pinterest eingeloggt ist; dies findet unabh\u00e4ngig davon statt, ob die betroffene Person die Pinterest-Komponente anklickt oder nicht. Ist eine derartige \u00dcbermittlung dieser Informationen an Pinterest von der betroffenen Person nicht gewollt, kann diese die \u00dcbermittlung dadurch verhindern, dass sie sich vor einem Aufruf unserer Internetseite aus ihrem Pinterest-Account ausloggt.<\/p>\n<p>Die von Pinterest ver\u00f6ffentlichte Datenschutzrichtlinie, die unter https:\/\/about.pinterest.com\/privacy-policy abrufbar ist, gibt Aufschluss \u00fcber die Erhebung, Verarbeitung und Nutzung personenbezogener Daten durch Pinterest.<\/p>\n<h4>20. Datenschutzbestimmungen zu Einsatz und Verwendung von Shariff<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite die Komponente Shariff integriert. Die Shariff-Komponente stellt Social-Media-Buttons zur Verf\u00fcgung, die datenschutzkonform sind. Shariff wurde f\u00fcr die deutsche Computerzeitschrift c&#8217;t entwickelt und wird \u00fcber die GitHub, Inc. publiziert.<\/p>\n<p>Entwickler der Komponente ist GitHub, Inc. 88 Colin P. Kelly Junior Street, San Francisco, CA 94107, USA.<\/p>\n<p>\u00dcblicherweise \u00fcbertragen die von den sozialen Netzwerken bereitgestellten Button-L\u00f6sungen bereits dann personenbezogene Daten an das jeweilige soziale Netzwerk, wenn ein Nutzer eine Internetseite besucht, in welche ein Social-Media-Button integriert wurde. Durch die Nutzung der Shariff-Komponente werden erst dann personenbezogene Daten an soziale Netzwerke \u00fcbermittelt, wenn der Besucher einer Internetseite aktiv einen der Social-Media-Buttons bet\u00e4tigt. Weitere Informationen zur Shariff-Komponente werden von der Computerzeitschrift c&#8217;t unter http:\/\/www.heise.de\/newsticker\/meldung\/Datenschutz-und-Social-Media-Der-c-t-Shariff-ist-im-Einsatz-2470103.html bereitgehalten. Der Einsatz der Shariff-Komponente hat den Zweck, die personenbezogenen Daten der Besucher unserer Internetseite zu sch\u00fctzen und uns gleichzeitig zu erm\u00f6glichen, eine Button-L\u00f6sung f\u00fcr soziale Netzwerke auf dieser Internetseite zu integrieren.<\/p>\n<p>Weitere Informationen und die geltenden Datenschutzbestimmungen von GitHub k\u00f6nnen unter https:\/\/help.github.com\/articles\/github-privacy-policy\/ abgerufen werden.<\/p>\n<h4>21. Datenschutzbestimmungen zu Einsatz und Verwendung von Twitter<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten von Twitter integriert. Twitter ist ein multilingualer \u00f6ffentlich zug\u00e4nglicher Mikroblogging-Dienst, auf welchem die Nutzer sogenannte Tweets, also Kurznachrichten, die auf 140 Zeichen begrenzt sind, ver\u00f6ffentlichen und verbreiten k\u00f6nnen. Diese Kurznachrichten sind f\u00fcr jedermann, also auch f\u00fcr nicht bei Twitter angemeldete Personen abrufbar. Die Tweets werden aber auch den sogenannten Followern des jeweiligen Nutzers angezeigt. Follower sind andere Twitter-Nutzer, die den Tweets eines Nutzers folgen. Ferner erm\u00f6glicht Twitter \u00fcber Hashtags, Verlinkungen oder Retweets die Ansprache eines breiten Publikums.<\/p>\n<p>Betreibergesellschaft von Twitter ist die Twitter, Inc., 1355 Market Street, Suite 900, San Francisco, CA 94103, USA.<\/p>\n<p>Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Twitter-Komponente (Twitter-Button) integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Twitter-Komponente veranlasst, eine Darstellung der entsprechenden Twitter-Komponente von Twitter herunterzuladen. Weitere Informationen zu den Twitter-Buttons sind unter https:\/\/about.twitter.com\/de\/resources\/buttons abrufbar. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Twitter Kenntnis dar\u00fcber, welche konkrete Unterseite unserer Internetseite durch die betroffene Person besucht wird. Zweck der Integration der Twitter-Komponente ist es, unseren Nutzern eine Weiterverbreitung der Inhalte diese Internetseite zu erm\u00f6glichen, diese Internetseite in der digitalen Welt bekannt zu machen und unsere Besucherzahlen zu erh\u00f6hen.<\/p>\n<p>Sofern die betroffene Person gleichzeitig bei Twitter eingeloggt ist, erkennt Twitter mit jedem Aufruf unserer Internetseite durch die betroffene Person und w\u00e4hrend der gesamten Dauer des jeweiligen Aufenthaltes auf unserer Internetseite, welche konkrete Unterseite unserer Internetseite die betroffene Person besucht. Diese Informationen werden durch die Twitter-Komponente gesammelt und durch Twitter dem jeweiligen Twitter-Account der betroffenen Person zugeordnet. Bet\u00e4tigt die betroffene Person einen der auf unserer Internetseite integrierten Twitter-Buttons, werden die damit \u00fcbertragenen Daten und Informationen dem pers\u00f6nlichen Twitter-Benutzerkonto der betroffenen Person zugeordnet und von Twitter gespeichert und verarbeitet.<\/p>\n<p>Twitter erh\u00e4lt \u00fcber die Twitter-Komponente immer dann eine Information dar\u00fcber, dass die betroffene Person unsere Internetseite besucht hat, wenn die betroffene Person zum Zeitpunkt des Aufrufs unserer Internetseite gleichzeitig bei Twitter eingeloggt ist; dies findet unabh\u00e4ngig davon statt, ob die betroffene Person die Twitter-Komponente anklickt oder nicht. Ist eine derartige \u00dcbermittlung dieser Informationen an Twitter von der betroffenen Person nicht gewollt, kann diese die \u00dcbermittlung dadurch verhindern, dass sie sich vor einem Aufruf unserer Internetseite aus ihrem Twitter-Account ausloggt.<\/p>\n<p>Die geltenden Datenschutzbestimmungen von Twitter sind unter https:\/\/twitter.com\/privacy?lang=de abrufbar.<\/p>\n<h4>22. Datenschutzbestimmungen zu Einsatz und Verwendung von YouTube<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten von YouTube integriert. YouTube ist ein Internet-Videoportal, dass Video-Publishern das kostenlose Einstellen von Videoclips und anderen Nutzern die ebenfalls kostenfreie Betrachtung, Bewertung und Kommentierung dieser erm\u00f6glicht. YouTube gestattet die Publikation aller Arten von Videos, weshalb sowohl komplette Film- und Fernsehsendungen, aber auch Musikvideos, Trailer oder von Nutzern selbst angefertigte Videos \u00fcber das Internetportal abrufbar sind.<\/p>\n<p>Betreibergesellschaft von YouTube ist die YouTube, LLC, 901 Cherry Ave., San Bruno, CA 94066, USA. Die YouTube, LLC ist einer Tochtergesellschaft der Google Inc., 1600 Amphitheatre Pkwy, Mountain View, CA 94043-1351, USA.<\/p>\n<p>Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine YouTube-Komponente (YouTube-Video) integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige YouTube-Komponente veranlasst, eine Darstellung der entsprechenden YouTube-Komponente von YouTube herunterzuladen. Weitere Informationen zu YouTube k\u00f6nnen unter https:\/\/www.youtube.com\/yt\/about\/de\/ abgerufen werden. Im Rahmen dieses technischen Verfahrens erhalten YouTube und Google Kenntnis dar\u00fcber, welche konkrete Unterseite unserer Internetseite durch die betroffene Person besucht wird.<\/p>\n<p>Sofern die betroffene Person gleichzeitig bei YouTube eingeloggt ist, erkennt YouTube mit dem Aufruf einer Unterseite, die ein YouTube-Video enth\u00e4lt, welche konkrete Unterseite unserer Internetseite die betroffene Person besucht. Diese Informationen werden durch YouTube und Google gesammelt und dem jeweiligen YouTube-Account der betroffenen Person zugeordnet.<\/p>\n<p>YouTube und Google erhalten \u00fcber die YouTube-Komponente immer dann eine Information dar\u00fcber, dass die betroffene Person unsere Internetseite besucht hat, wenn die betroffene Person zum Zeitpunkt des Aufrufs unserer Internetseite gleichzeitig bei YouTube eingeloggt ist; dies findet unabh\u00e4ngig davon statt, ob die betroffene Person ein YouTube-Video anklickt oder nicht. Ist eine derartige \u00dcbermittlung dieser Informationen an YouTube und Google von der betroffenen Person nicht gewollt, kann diese die \u00dcbermittlung dadurch verhindern, dass sie sich vor einem Aufruf unserer Internetseite aus ihrem YouTube-Account ausloggt.<\/p>\n<p>Die von YouTube ver\u00f6ffentlichten Datenschutzbestimmungen, die unter https:\/\/www.google.de\/intl\/de\/policies\/privacy\/ abrufbar sind, geben Aufschluss \u00fcber die Erhebung, Verarbeitung und Nutzung personenbezogener Daten durch YouTube und Google.<\/p>\n<h4>23. Datenschutzbestimmungen zu Einsatz und Verwendung von DoubleClick<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten von DoubleClick by Google integriert. DoubleClick ist eine Marke von Google, unter welcher vorwiegend spezielle Online-Marketing-L\u00f6sungen an Werbeagenturen und Verlage vermarktet werden.<\/p>\n<p>Betreibergesellschaft von DoubleClick by Google ist die Google Inc., 1600 Amphitheatre Pkwy, Mountain View, CA 94043-1351, USA.<\/p>\n<p>DoubleClick by Google \u00fcbertr\u00e4gt sowohl mit jeder Impression als auch mit Klicks oder anderen Aktivit\u00e4ten Daten auf den DoubleClick-Server. Jede dieser Daten\u00fcbertragungen l\u00f6st eine Cookie-Anfrage an den Browser der betroffenen Person aus. Akzeptiert der Browser diese Anfrage, setzt DoubleClick ein Cookie auf dem informationstechnologischen System der betroffenen Person. Was Cookies sind, wurde oben bereits erl\u00e4utert. Zweck des Cookies ist die Optimierung und Einblendung von Werbung. Das Cookie wird unter anderem dazu verwendet, nutzerrelevante Werbung zu schalten und anzuzeigen sowie um Berichte zu Werbekampagnen zu erstellen oder diese zu verbessern. Ferner dient das Cookie dazu, Mehrfacheinblendungen derselben Werbung zu vermeiden.<\/p>\n<p>DoubleClick verwendet eine Cookie-ID, die zur Abwicklung des technischen Verfahrens erforderlich ist. Die Cookie-ID wird beispielsweise ben\u00f6tigt, um eine Werbeanzeige in einem Browser anzuzeigen. DoubleClick kann \u00fcber die Cookie-ID zudem erfassen, welche Werbeanzeigen bereits in einem Browser eingeblendet wurden, um Doppelschaltungen zu vermeiden. Ferner ist es DoubleClick durch die Cookie-ID m\u00f6glich, Conversions zu erfassen. Conversions werden beispielsweise dann erfasst, wenn einem Nutzer zuvor eine DoubleClick-Werbeanzeige eingeblendet wurde und dieser in der Folge mit dem gleichen Internetbrowser einen Kauf auf der Internetseite des Werbetreibenden vollzieht.<\/p>\n<p>Ein Cookie von DoubleClick enth\u00e4lt keine personenbezogenen Daten. Ein DoubleClick-Cookie kann aber zus\u00e4tzliche Kampagnen-Kennungen enthalten. Eine Kampagnen-Kennung dient einer Identifizierung der Kampagnen, mit denen der Nutzer bereits in Kontakt war.<\/p>\n<p>Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine DoubleClick-Komponente integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige DoubleClick-Komponente veranlasst, Daten zum Zwecke der Online-Werbung und der Abrechnung von Provisionen an Google zu \u00fcbermitteln. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Google Kenntnis \u00fcber Daten, die Google auch dazu dienen, Provisionsabrechnungen zu erstellen. Google kann unter anderem nachvollziehen, dass die betroffene Person bestimmte Links auf unserer Internetseite angeklickt hat.<\/p>\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass Google ein Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem k\u00f6nnen von Google bereits gesetzte Cookies jederzeit \u00fcber einen Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.<\/p>\n<p>Weitere Informationen und die geltenden Datenschutzbestimmungen von DoubleClick by Google k\u00f6nnen unter https:\/\/www.google.com\/intl\/de\/policies\/ abgerufen werden.<\/p>\n<h4>24. Datenschutzbestimmungen zu Einsatz und Verwendung von Zanox<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten von Zanox integriert. Zanox ist ein deutsches Affiliate-Netzwerk, welches Affiliate-Marketing anbietet. Affiliate-Marketing ist eine Internetgest\u00fctzte Vertriebsform, die es kommerziellen Betreibern von Internetseiten, den sogenannten Merchants oder Advertisern, erm\u00f6glicht, Werbung, die meist \u00fcber Klick- oder Sale-Provisionen verg\u00fctet wird, auf Internetseiten Dritter, also bei Vertriebspartnern, die auch Affiliates oder Publisher genannt werden, einzublenden. Der Merchant stellt \u00fcber das Affiliate-Netzwerk ein Werbemittel, also einen Werbebanner oder andere geeignete Mittel der Internetwerbung zur Verf\u00fcgung, welche in der Folge von einem Affiliate auf eigenen Internetseiten eingebunden oder \u00fcber sonstige Kan\u00e4le, wie etwa das Keyword-Advertising oder E-Mail-Marketing, beworben werden.<\/p>\n<p>Betreibergesellschaft von Zanox ist die ZANOX AG, Stralauer Allee 2, 10245 Berlin, Deutschland.<\/p>\n<p>Zanox setzt ein Cookie auf dem informationstechnologischen System der betroffenen Person. Was Cookies sind, wurde oben bereits erl\u00e4utert. Der Tracking-Cookie von Zanox speichert keinerlei personenbezogene Daten. Gespeichert werden lediglich die Identifikationsnummer des Affiliate, also des den potentiellen Kunden vermittelnden Partners, sowie die Ordnungsnummer des Besuchers einer Internetseite und des angeklickten Werbemittels. Zweck der Speicherung dieser Daten ist die Abwicklung von Provisionszahlungen zwischen einem Merchant und dem Affiliate, welche \u00fcber das Affiliate-Netzwerk, also Zanox, abgewickelt werden.<\/p>\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass Zanox ein Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem k\u00f6nnen von Zanox bereits gesetzte Cookies jederzeit \u00fcber einen Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.<\/p>\n<p>Die geltenden Datenschutzbestimmungen von Zanox k\u00f6nnen unter http:\/\/www.zanox.com\/de\/ueber-zanox\/datenschutz\/ abgerufen werden.<\/p>\n<h4>25. Datenschutzbestimmungen zu Einsatz und Verwendung von Belboon<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten von Belboon integriert. Belboon ist ein deutsches Affiliate-Netzwerk, welches Affiliate-Marketing anbietet. Affiliate-Marketing ist eine Internetgest\u00fctzte Vertriebsform, die es kommerziellen Betreibern von Internetseiten, den sogenannten Merchants oder Advertisern, erm\u00f6glicht, Werbung, die meist \u00fcber Klick- oder Sale-Provisionen verg\u00fctet wird, auf Internetseiten Dritter, also bei Vertriebspartnern, die auch Affiliates oder Publisher genannt werden, einzublenden. Der Merchant stellt \u00fcber das Affiliate-Netzwerk ein Werbemittel, also einen Werbebanner oder andere geeignete Mittel der Internetwerbung zur Verf\u00fcgung, welche in der Folge von einem Affiliate auf eigenen Internetseiten eingebunden oder \u00fcber sonstige Kan\u00e4le, wie etwa das Keyword-Advertising oder E-Mail-Marketing, beworben werden.<\/p>\n<p>Betreibergesellschaft von Adcell ist die belboon GmbH, Weinmeisterstr. 12-14, 10178 Berlin.<\/p>\n<p>Belboon setzt ein Cookie auf dem informationstechnologischen System der betroffenen Person. Was Cookies sind, wurde oben bereits erl\u00e4utert. Der Tracking-Cookie von Belboon speichert keinerlei personenbezogene Daten. Gespeichert werden lediglich die Identifikationsnummer des Affiliate, also des den potentiellen Kunden vermittelnden Partners, sowie die Ordnungsnummer des Besuchers einer Internetseite und des angeklickten Werbemittels. Zweck der Speicherung dieser Daten ist die Abwicklung von Provisionszahlungen zwischen einem Merchant und dem Affiliate, welche \u00fcber das Affiliate-Netzwerk, also Belboon, abgewickelt werden.<\/p>\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass Belboon ein Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem k\u00f6nnen von Belboon bereits gesetzte Cookies jederzeit \u00fcber einen Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.<\/p>\n<p>Die geltenden Datenschutzbestimmungen von Belboon k\u00f6nnen unter https:\/\/www.belboon.com\/de\/ueber-uns\/datenschutz\/ abgerufen werden.<\/p>\n<h4>26. Datenschutzbestimmungen zu Einsatz und Verwendung von Tradedoubler<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite Komponenten von Tradedoubler integriert. Tradedoubler ist ein deutsches Affiliate-Netzwerk, welches Affiliate-Marketing anbietet. Affiliate-Marketing ist eine Internetgest\u00fctzte Vertriebsform, die es kommerziellen Betreibern von Internetseiten, den sogenannten Merchants oder Advertisern, erm\u00f6glicht, Werbung, die meist \u00fcber Klick- oder Sale-Provisionen verg\u00fctet wird, auf Internetseiten Dritter, also bei Vertriebspartnern, die auch Affiliates oder Publisher genannt werden, einzublenden. Der Merchant stellt \u00fcber das Affiliate-Netzwerk ein Werbemittel, also einen Werbebanner oder andere geeignete Mittel der Internetwerbung, zur Verf\u00fcgung, welche in der Folge von einem Affiliate auf eigenen Internetseiten eingebunden oder \u00fcber sonstige Kan\u00e4le, wie etwa das Keyword-Advertising oder E-Mail-Marketing, beworben werden.<\/p>\n<p>Betreibergesellschaft von Tradedoubler ist die Tradedoubler GmbH, Herzog-Wilhelm-Stra\u00dfe 26, 80331 M\u00fcnchen, Deutschland.<\/p>\n<p>Tradedoubler setzt ein Cookie auf dem informationstechnologischen System der betroffenen Person. Was Cookies sind, wurde oben bereits erl\u00e4utert. Der Tracking-Cookie von Tradedoubler speichert keinerlei personenbezogene Daten. Gespeichert werden lediglich die Identifikationsnummer des Affiliate, also des den potentiellen Kunden vermittelnden Partners, sowie die Ordnungsnummer des Besuchers einer Internetseite und des angeklickten Werbemittels. Zweck der Speicherung dieser Daten ist die Abwicklung von Provisionszahlungen zwischen einem Merchant und dem Affiliate, welche \u00fcber das Affiliate-Netzwerk, also Tradedoubler, abgewickelt werden.<\/p>\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass Tradedoubler ein Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem k\u00f6nnen von Tradedoubler bereits gesetzte Cookies jederzeit \u00fcber einen Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.<\/p>\n<p>Die geltenden Datenschutzbestimmungen von Tradedoubler k\u00f6nnen unter http:\/\/www.tradedoubler.com\/de\/datenschutzrichtlinie\/ abgerufen werden.<\/p>\n<h4>27. Rechtsgrundlage der Verarbeitung<\/h4>\n<p>Art. 6 I lit. a DS-GVO dient unserem Unternehmen als Rechtsgrundlage f\u00fcr Verarbeitungsvorg\u00e4nge, bei denen wir eine Einwilligung f\u00fcr einen bestimmten Verarbeitungszweck einholen. Ist die Verarbeitung personenbezogener Daten zur Erf\u00fcllung eines Vertrags, dessen Vertragspartei die betroffene Person ist, erforderlich, wie dies beispielsweise bei Verarbeitungsvorg\u00e4ngen der Fall ist, die f\u00fcr eine Lieferung von Waren oder die Erbringung einer sonstigen Leistung oder Gegenleistung notwendig sind, so beruht die Verarbeitung auf Art. 6 I lit. b DS-GVO. Gleiches gilt f\u00fcr solche Verarbeitungsvorg\u00e4nge die zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich sind, etwa in F\u00e4llen von Anfragen zur unseren Produkten oder Leistungen. Unterliegt unser Unternehmen einer rechtlichen Verpflichtung durch welche eine Verarbeitung von personenbezogenen Daten erforderlich wird, wie beispielsweise zur Erf\u00fcllung steuerlicher Pflichten, so basiert die Verarbeitung auf Art. 6 I lit. c DS-GVO. In seltenen F\u00e4llen k\u00f6nnte die Verarbeitung von personenbezogenen Daten erforderlich werden, um lebenswichtige Interessen der betroffenen Person oder einer anderen nat\u00fcrlichen Person zu sch\u00fctzen. Dies w\u00e4re beispielsweise der Fall, wenn ein Besucher in unserem Betrieb verletzt werden w\u00fcrde und daraufhin sein Name, sein Alter, seine Krankenkassendaten oder sonstige lebenswichtige Informationen an einen Arzt, ein Krankenhaus oder sonstige Dritte weitergegeben werden m\u00fcssten. Dann w\u00fcrde die Verarbeitung auf Art. 6 I lit. d DS-GVO beruhen.<br \/>\nLetztlich k\u00f6nnten Verarbeitungsvorg\u00e4nge auf Art. 6 I lit. f DS-GVO beruhen. Auf dieser Rechtsgrundlage basieren Verarbeitungsvorg\u00e4nge, die von keiner der vorgenannten Rechtsgrundlagen erfasst werden, wenn die Verarbeitung zur Wahrung eines berechtigten Interesses unseres Unternehmens oder eines Dritten erforderlich ist, sofern die Interessen, Grundrechte und Grundfreiheiten des Betroffenen nicht \u00fcberwiegen. Solche Verarbeitungsvorg\u00e4nge sind uns insbesondere deshalb gestattet, weil sie durch den Europ\u00e4ischen Gesetzgeber besonders erw\u00e4hnt wurden. Er vertrat insoweit die Auffassung, dass ein berechtigtes Interesse anzunehmen sein k\u00f6nnte, wenn die betroffene Person ein Kunde des Verantwortlichen ist (Erw\u00e4gungsgrund 47 Satz 2 DS-GVO).\n<\/p>\n<h4>28. Berechtigte Interessen an der Verarbeitung, die von dem Verantwortlichen oder einem Dritten verfolgt werden<\/h4>\n<p>Basiert die Verarbeitung personenbezogener Daten auf Artikel 6 I lit. f DS-GVO ist unser berechtigtes Interesse die Durchf\u00fchrung unserer Gesch\u00e4ftst\u00e4tigkeit zugunsten des Wohlergehens all unserer Mitarbeiter und unserer Anteilseigner.<\/p>\n<h4>29. Dauer, f\u00fcr die die personenbezogenen Daten gespeichert werden<\/h4>\n<p>Das Kriterium f\u00fcr die Dauer der Speicherung von personenbezogenen Daten ist die jeweilige gesetzliche Aufbewahrungsfrist. Nach Ablauf der Frist werden die entsprechenden Daten routinem\u00e4\u00dfig gel\u00f6scht, sofern sie nicht mehr zur Vertragserf\u00fcllung oder Vertragsanbahnung erforderlich sind.<\/p>\n<h4>30. Gesetzliche oder vertragliche Vorschriften zur Bereitstellung der personenbezogenen Daten; Erforderlichkeit f\u00fcr den Vertragsabschluss; Verpflichtung der betroffenen Person, die personenbezogenen Daten bereitzustellen; m\u00f6gliche Folgen der Nichtbereitstellung<\/h4>\n<p>Wir kl\u00e4ren Sie dar\u00fcber auf, dass die Bereitstellung personenbezogener Daten zum Teil gesetzlich vorgeschrieben ist (z.B. Steuervorschriften) oder sich auch aus vertraglichen Regelungen (z.B. Angaben zum Vertragspartner) ergeben kann.<br \/>\nMitunter kann es zu einem Vertragsschluss erforderlich sein, dass eine betroffene Person uns personenbezogene Daten zur Verf\u00fcgung stellt, die in der Folge durch uns verarbeitet werden m\u00fcssen. Die betroffene Person ist beispielsweise verpflichtet uns personenbezogene Daten bereitzustellen, wenn unser Unternehmen mit ihr einen Vertrag abschlie\u00dft. Eine Nichtbereitstellung der personenbezogenen Daten h\u00e4tte zur Folge, dass der Vertrag mit dem Betroffenen nicht geschlossen werden k\u00f6nnte.<br \/>\nVor einer Bereitstellung personenbezogener Daten durch den Betroffenen muss sich der Betroffene an unseren Datenschutzbeauftragten wenden. Unser Datenschutzbeauftragter kl\u00e4rt den Betroffenen einzelfallbezogen dar\u00fcber auf, ob die Bereitstellung der personenbezogenen Daten gesetzlich oder vertraglich vorgeschrieben oder f\u00fcr den Vertragsabschluss erforderlich ist, ob eine Verpflichtung besteht, die personenbezogenen Daten bereitzustellen, und welche Folgen die Nichtbereitstellung der personenbezogenen Daten h\u00e4tte.\n<\/p>\n<h4>31. Bestehen einer automatisierten Entscheidungsfindung<\/h4>\n<p>Als verantwortungsbewusstes Unternehmen verzichten wir auf eine automatische Entscheidungsfindung oder ein Profiling.<\/p>\n<p>Diese Datenschutzerkl\u00e4rung wurde durch den Datenschutzerkl\u00e4rungs-Generator der DGD Deutsche Gesellschaft f\u00fcr Datenschutz GmbH, die als <a href=\"https:\/\/dg-datenschutz.de\/datenschutz-dienstleistungen\/externer-datenschutzbeauftragter\/\" rel=\"nofollow\">Externer Datenschutzbeauftragter Hamburg<\/a> t\u00e4tig ist, in Kooperation mit dem <a href=\"https:\/\/www.wbs-law.de\/\" rel=\"nofollow\">Datenschutz Anwalt Christian Solmecke<\/a> erstellt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Datenschutzerkl\u00e4rung Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung der shopping-club.com. Eine Nutzung der Internetseiten der shopping-club.com ist grunds\u00e4tzlich (&hellip;) <a href=\"https:\/\/www.shopping-club.com\/de\/datenschutzerklaerung\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-250","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Datenschutzerkl\u00e4rung Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung der shopping-club.com. Eine Nutzung der Internetseiten der shopping-club.com ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch eine Verarbeitung\" \/>\n\t<meta name=\"robots\" content=\"noindex, nofollow, max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.shopping-club.com\/de\/datenschutzerklaerung\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Shopping Club\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Datenschutzerkl\u00e4rung - Shopping Club\" \/>\n\t\t<meta property=\"og:description\" content=\"Datenschutzerkl\u00e4rung Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung der shopping-club.com. Eine Nutzung der Internetseiten der shopping-club.com ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch eine Verarbeitung\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.shopping-club.com\/de\/datenschutzerklaerung\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.shopping-club.com\/de\/wp-content\/uploads\/2014\/03\/kumk.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.shopping-club.com\/de\/wp-content\/uploads\/2014\/03\/kumk.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"270\" \/>\n\t\t<meta property=\"og:image:height\" content=\"251\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-05-15T20:31:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-02-23T22:50:58+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Datenschutzerkl\u00e4rung - Shopping Club\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Datenschutzerkl\u00e4rung Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung der shopping-club.com. Eine Nutzung der Internetseiten der shopping-club.com ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch eine Verarbeitung\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.shopping-club.com\/de\/wp-content\/uploads\/2014\/03\/kumk.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.shopping-club.com\\\/de\\\/datenschutzerklaerung#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.shopping-club.com\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.shopping-club.com\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.shopping-club.com\\\/de\\\/datenschutzerklaerung#listItem\",\"name\":\"Datenschutzerkl\\u00e4rung\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.shopping-club.com\\\/de\\\/datenschutzerklaerung#listItem\",\"position\":2,\"name\":\"Datenschutzerkl\\u00e4rung\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.shopping-club.com\\\/de#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.shopping-club.com\\\/de\\\/#organization\",\"name\":\"deutsche Shopping Clubs\",\"description\":\"deutsche Shopping Clubs - alle geschlossene Shopping Communities\",\"url\":\"https:\\\/\\\/www.shopping-club.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.shopping-club.com\\\/de\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/kumk-de.jpg\",\"@id\":\"https:\\\/\\\/www.shopping-club.com\\\/de\\\/datenschutzerklaerung\\\/#organizationLogo\",\"width\":600,\"height\":600},\"image\":{\"@id\":\"https:\\\/\\\/www.shopping-club.com\\\/de\\\/datenschutzerklaerung\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.shopping-club.com\\\/de\\\/datenschutzerklaerung#webpage\",\"url\":\"https:\\\/\\\/www.shopping-club.com\\\/de\\\/datenschutzerklaerung\",\"name\":\"Datenschutzerkl\\u00e4rung - Shopping Club\",\"description\":\"Datenschutzerkl\\u00e4rung Wir freuen uns sehr \\u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\\u00fcr die Gesch\\u00e4ftsleitung der shopping-club.com. Eine Nutzung der Internetseiten der shopping-club.com ist grunds\\u00e4tzlich ohne jede Angabe personenbezogener Daten m\\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \\u00fcber unsere Internetseite in Anspruch nehmen m\\u00f6chte, k\\u00f6nnte jedoch eine Verarbeitung\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shopping-club.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.shopping-club.com\\\/de\\\/datenschutzerklaerung#breadcrumblist\"},\"datePublished\":\"2018-05-15T22:31:29+02:00\",\"dateModified\":\"2020-02-24T00:50:58+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.shopping-club.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.shopping-club.com\\\/de\\\/\",\"name\":\"Shopping Club\",\"description\":\"deutsche Shopping Clubs - alle geschlossene Shopping Communities\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.shopping-club.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Datenschutzerkl\u00e4rung - Shopping Club","description":"Datenschutzerkl\u00e4rung Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung der shopping-club.com. Eine Nutzung der Internetseiten der shopping-club.com ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch eine Verarbeitung","canonical_url":"https:\/\/www.shopping-club.com\/de\/datenschutzerklaerung","robots":"noindex, nofollow, max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.shopping-club.com\/de\/datenschutzerklaerung#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.shopping-club.com\/de#listItem","position":1,"name":"Home","item":"https:\/\/www.shopping-club.com\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/www.shopping-club.com\/de\/datenschutzerklaerung#listItem","name":"Datenschutzerkl\u00e4rung"}},{"@type":"ListItem","@id":"https:\/\/www.shopping-club.com\/de\/datenschutzerklaerung#listItem","position":2,"name":"Datenschutzerkl\u00e4rung","previousItem":{"@type":"ListItem","@id":"https:\/\/www.shopping-club.com\/de#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/www.shopping-club.com\/de\/#organization","name":"deutsche Shopping Clubs","description":"deutsche Shopping Clubs - alle geschlossene Shopping Communities","url":"https:\/\/www.shopping-club.com\/de\/","logo":{"@type":"ImageObject","url":"https:\/\/www.shopping-club.com\/de\/wp-content\/uploads\/2015\/12\/kumk-de.jpg","@id":"https:\/\/www.shopping-club.com\/de\/datenschutzerklaerung\/#organizationLogo","width":600,"height":600},"image":{"@id":"https:\/\/www.shopping-club.com\/de\/datenschutzerklaerung\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/www.shopping-club.com\/de\/datenschutzerklaerung#webpage","url":"https:\/\/www.shopping-club.com\/de\/datenschutzerklaerung","name":"Datenschutzerkl\u00e4rung - Shopping Club","description":"Datenschutzerkl\u00e4rung Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung der shopping-club.com. Eine Nutzung der Internetseiten der shopping-club.com ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch eine Verarbeitung","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.shopping-club.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/www.shopping-club.com\/de\/datenschutzerklaerung#breadcrumblist"},"datePublished":"2018-05-15T22:31:29+02:00","dateModified":"2020-02-24T00:50:58+02:00"},{"@type":"WebSite","@id":"https:\/\/www.shopping-club.com\/de\/#website","url":"https:\/\/www.shopping-club.com\/de\/","name":"Shopping Club","description":"deutsche Shopping Clubs - alle geschlossene Shopping Communities","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.shopping-club.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Shopping Club","og:type":"article","og:title":"Datenschutzerkl\u00e4rung - Shopping Club","og:description":"Datenschutzerkl\u00e4rung Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung der shopping-club.com. Eine Nutzung der Internetseiten der shopping-club.com ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch eine Verarbeitung","og:url":"https:\/\/www.shopping-club.com\/de\/datenschutzerklaerung","og:image":"https:\/\/www.shopping-club.com\/de\/wp-content\/uploads\/2014\/03\/kumk.jpg","og:image:secure_url":"https:\/\/www.shopping-club.com\/de\/wp-content\/uploads\/2014\/03\/kumk.jpg","og:image:width":270,"og:image:height":251,"article:published_time":"2018-05-15T20:31:29+00:00","article:modified_time":"2020-02-23T22:50:58+00:00","twitter:card":"summary","twitter:title":"Datenschutzerkl\u00e4rung - Shopping Club","twitter:description":"Datenschutzerkl\u00e4rung Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung der shopping-club.com. Eine Nutzung der Internetseiten der shopping-club.com ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch eine Verarbeitung","twitter:image":"https:\/\/www.shopping-club.com\/de\/wp-content\/uploads\/2014\/03\/kumk.jpg"},"aioseo_meta_data":{"post_id":"250","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":"","og_description":"","og_object_type":"article","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":false,"robots_noindex":true,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":true,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 22:39:53","updated":"2025-06-03 22:50:55","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.shopping-club.com\/de\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDatenschutzerkl\u00e4rung\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.shopping-club.com\/de"},{"label":"Datenschutzerkl\u00e4rung","link":"https:\/\/www.shopping-club.com\/de\/datenschutzerklaerung"}],"_links":{"self":[{"href":"https:\/\/www.shopping-club.com\/de\/wp-json\/wp\/v2\/pages\/250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shopping-club.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.shopping-club.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.shopping-club.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shopping-club.com\/de\/wp-json\/wp\/v2\/comments?post=250"}],"version-history":[{"count":5,"href":"https:\/\/www.shopping-club.com\/de\/wp-json\/wp\/v2\/pages\/250\/revisions"}],"predecessor-version":[{"id":307,"href":"https:\/\/www.shopping-club.com\/de\/wp-json\/wp\/v2\/pages\/250\/revisions\/307"}],"wp:attachment":[{"href":"https:\/\/www.shopping-club.com\/de\/wp-json\/wp\/v2\/media?parent=250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}